{"id":3445,"date":"2021-01-20T12:24:10","date_gmt":"2021-01-20T17:24:10","guid":{"rendered":"https:\/\/www-test.absglobal.com\/co\/?post_type=abs_news_article&#038;p=3445"},"modified":"2021-01-20T12:24:11","modified_gmt":"2021-01-20T17:24:11","slug":"uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus","status":"publish","type":"abs_news_article","link":"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/","title":{"rendered":"Uruguay celebra la comercializaci\u00f3n de los primeros terneros Beef InFocus"},"content":{"rendered":"\n<p><em>Un a\u00f1o despu\u00e9s del lanzamiento de la tecnolog\u00eda innovadora de ABS, una asociaci\u00f3n con Berrutti United Breeders &amp; Packers ya muestra su potencial, dirigiendo a los terneros Beef InFocus NuEra a la cadena de producci\u00f3n de carne<\/em>&nbsp;<\/p>\n\n\n\n<p>Las \u00faltimas semanas de 2020 trajeron algo nuevo que movi\u00f3 a ABS y consolid\u00f3 uno de sus productos m\u00e1s recientes en el mercado uruguayo: la comercializaci\u00f3n de los primeros terneros nacidos como resultado del uso de Beef InFocus, la innovadora soluci\u00f3n de carne en leche de la compa\u00f1\u00eda.&nbsp;<\/p>\n\n\n\n<p>La novedad ocurri\u00f3 aproximadamente un a\u00f1o despu\u00e9s del lanzamiento del producto en el pa\u00eds. En Uruguay, el lanzamiento de Beef InFocus estuvo acompa\u00f1ado de una alianza con Berrutti United Breeders &amp; Packers, empresa que se encargaba de la adquisici\u00f3n de terneros <em>Beef InFocus NuEra<\/em> creados por la gen\u00e9tica especial de carne en leche desarrollada por ABS.&nbsp;<\/p>\n\n\n\n<p>Luego de las primeras inseminaciones, la expectativa por conocer el perfil y caracter\u00edsticas de los animales Beef InFocus fue muy alta, debido al gran potencial de la tecnolog\u00eda y el impacto esperado en ambas cadenas productivas &#8211; leche y carne.&nbsp;<\/p>\n\n\n\n<p>El gerente de Beef InFocus de ABS Uruguay, Pablo Harispe, revela que el primer lote adquirido por Berrutti provino del reba\u00f1o de Firma Ballesta y Rovira de Canelones, compuesto por 14 terneros de la l\u00ednea T14. El resultado sorprendi\u00f3 al productor desde el momento del parto.&nbsp;<\/p>\n\n\n\n<p>\u201cEl promedio estimado para estos animales fue de 170 kg, pero de hecho llegaron a 209 kg, lo que ya muestra su calidad para la cadena c\u00e1rnica. Son animales negros, machos y homocigotos, con una gestaci\u00f3n m\u00e1s corta y mayor resistencia. adem\u00e1s, por supuesto, de una calidad diferenciada para su inserci\u00f3n en el mercado c\u00e1rnico\u201d, destaca el gerente.&nbsp;<\/p>\n\n\n\n<p>El productor tambi\u00e9n destac\u00f3 la facilidad de adaptaci\u00f3n de los terneros j\u00f3venes, llamando tambi\u00e9n la atenci\u00f3n sobre el parto sin problemas y la mansedumbre de los animales.&nbsp;<\/p>\n\n\n\n<p>\u201cSon productos especialmente desarrollados con una gen\u00e9tica \u00fanica, proveniente de nuestro n\u00facleo NuEra. Los partos tuvieron lugar en julio y, en los primeros d\u00edas de noviembre, ya estaban preparados para ser adquiridos por Berrutti. Sin duda es un resultado que nos motiva a\u00fan m\u00e1s. Estamos inspirados para sacar adelante este proyecto, confiados en que todav\u00eda tenemos mucho que celebrar en el futuro\u201d, confirma Pablo.&nbsp;<\/p>\n\n\n\n<p>El director de Berrutti United Breeders &amp; Packers, Alejandro Berrutti, tambi\u00e9n celebr\u00f3 la calidad de los animales nacidos, destacando el valor de la asociaci\u00f3n con ABS.&nbsp;<\/p>\n\n\n\n<p>\u201cEstoy muy agradecido por el tipo de terneros que nacieron, con un biotipo claramente carnicero, con vitalidad similar al ganado puro Angus. Nuestro equipo t\u00e9cnico tambi\u00e9n nos inform\u00f3 que los animales se adaptaron muy f\u00e1cilmente a la dieta y tambi\u00e9n mostraron mucha docilidad\u201d, eval\u00faa Berrutti.&nbsp;<\/p>\n\n\n\n<p>Seg\u00fan el gerente de Cuentas Estrat\u00e9gicas para Am\u00e9rica Latina de ABS, Luis Adriano Teixeira, la expectativa es que la producci\u00f3n se multiplique a medida que sucedan m\u00e1s partos, dando lugar a m\u00e1s terneros para el corral Berrutti.&nbsp;<\/p>\n\n\n\n<p>\u201cEstimamos que en Uruguay circulan unas 10.000 dosis, que pueden generar entre 3,5 y 4 mil terneros Beef InFocus en un per\u00edodo de hasta 12 meses, con una capacidad de generar un valor agregado extra al tambero de cerca de 33% cuando comparado al valor del macho 100% lechero\u201d, calcula el gerente.&nbsp;<\/p>\n\n\n\n<p>Pablo Harispe refuerza las posibilidades que representa Beef InFocus para las cadenas l\u00e1cteas y c\u00e1rnicas uruguayas, as\u00ed como para el productor.&nbsp;<\/p>\n\n\n\n<p>\u201cEs una oportunidad sin precedentes para el productor de leche. Las mejores vacas del reba\u00f1o se pueden multiplicar a trav\u00e9s de la gen\u00e9tica sexada Sexcel, mientras que las de menor valor gen\u00e9tico se inseminan con semen Beef InFocus, dando lugar a terneros aptos para la cadena de producci\u00f3n c\u00e1rnica. As\u00ed, estamos creando, validando y generando valor con una gen\u00e9tica probada, trazada y certificada\u201d, describe Harispe.&nbsp;<\/p>\n\n\n\n<p><strong>Beef InFocus.<\/strong> Lanzado el a\u00f1o pasado en Uruguay, luego del \u00e9xito verificado por ABS en otros pa\u00edses, Beef InFocus es una soluci\u00f3n innovadora para los productores de leche, capaz de ofrecer un destino a las vacas menos productivas del reba\u00f1o. Antes, las hembras con bajo valor gen\u00e9tico terminaban siendo descartadas, provocando da\u00f1os al criador.&nbsp;<\/p>\n\n\n\n<p>Al utilizar Beef InFocus, el productor garantiza que incluso las hembras con menor capacidad de producci\u00f3n pueden contribuir a la rentabilidad de la lecher\u00eda, a trav\u00e9s de la generaci\u00f3n de terneros h\u00edbridos con caracter\u00edsticas deseables para la cadena c\u00e1rnica, beneficiando a ambos sectores con una tecnolog\u00eda \u00fanica.&nbsp;<\/p>\n\n\n\n<p>Beef InFocus es impulsado por NuEra Genetics, el motor gen\u00e9tico detr\u00e1s de la tecnolog\u00eda. Los toros utilizados en la inseminaci\u00f3n se seleccionan de acuerdo a su clasificaci\u00f3n en el \u00edndice Beef Advantage, que eval\u00faa a los animales seg\u00fan su capacidad para generar terneros de alta calidad para la cadena de suministro de carne.&nbsp;<\/p>\n\n\n\n<p>En Uruguay, el destino de estos terneros est\u00e1 asegurado por la alianza con Berrutti United Breeders &amp; Packers, que se encarg\u00f3 de la adquisici\u00f3n de estos animales, asegurando al productor lechero que los partos h\u00edbridos ya nacen con un destino determinado, consolidando una segunda fuente de ingresos y asegurando la oferta de animales de calidad para el mercado c\u00e1rnico.&nbsp;<\/p>\n\n\n\n<p>&#8220;Es un proyecto revolucionario que est\u00e1 en l\u00ednea con el mundo conectado y cambiante en el que vivimos&#8221;, concluye Pablo Harispe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un a\u00f1o despu\u00e9s del lanzamiento de la tecnolog\u00eda innovadora de ABS, una asociaci\u00f3n con Berrutti United Breeders &amp; Packers ya muestra su potencial, dirigiendo a los terneros Beef InFocus NuEra a la cadena de producci\u00f3n de carne&nbsp; Las \u00faltimas semanas de 2020 trajeron algo nuevo que movi\u00f3 a ABS y consolid\u00f3 uno de sus productos [&hellip;]<\/p>\n","protected":false},"author":342,"featured_media":3446,"template":"","abs_news_category":[101],"abs_news_tag":[106,104],"class_list":["post-3445","abs_news_article","type-abs_news_article","status-publish","has-post-thumbnail","hentry","abs_news_category-noticias","abs_news_tag-carne","abs_news_tag-leche","ep_custom_result-carne","ep_custom_result-leche"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Uruguay celebra la comercializaci\u00f3n de los primeros terneros Beef InFocus - ABS Global Colombia<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uruguay celebra la comercializaci\u00f3n de los primeros terneros Beef InFocus\" \/>\n<meta property=\"og:description\" content=\"Un a\u00f1o despu\u00e9s del lanzamiento de la tecnolog\u00eda innovadora de ABS, una asociaci\u00f3n con Berrutti United Breeders &amp; Packers ya muestra su potencial, dirigiendo a los terneros Beef InFocus NuEra a la cadena de producci\u00f3n de carne&nbsp; Las \u00faltimas semanas de 2020 trajeron algo nuevo que movi\u00f3 a ABS y consolid\u00f3 uno de sus productos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Colombia\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-20T17:24:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-test.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2021\/01\/WhatsApp-Image-2020-12-15-at-09.55.01.jpeg?fit=1600%2C1066\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/\",\"url\":\"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/\",\"name\":\"Uruguay celebra la comercializaci\u00f3n de los primeros terneros Beef InFocus - ABS Global Colombia\",\"isPartOf\":{\"@id\":\"https:\/\/www-test.absglobal.com\/co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www-test.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2021\/01\/WhatsApp-Image-2020-12-15-at-09.55.01.jpeg\",\"datePublished\":\"2021-01-20T17:24:10+00:00\",\"dateModified\":\"2021-01-20T17:24:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/#primaryimage\",\"url\":\"https:\/\/www-test.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2021\/01\/WhatsApp-Image-2020-12-15-at-09.55.01.jpeg\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2021\/01\/WhatsApp-Image-2020-12-15-at-09.55.01.jpeg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-test.absglobal.com\/co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News Articles\",\"item\":\"https:\/\/www-test.absglobal.com\/co\/articles\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Uruguay celebra la comercializaci\u00f3n de los primeros terneros Beef InFocus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-test.absglobal.com\/co\/#website\",\"url\":\"https:\/\/www-test.absglobal.com\/co\/\",\"name\":\"ABS Global Colombia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-test.absglobal.com\/co\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-test.absglobal.com\/co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-test.absglobal.com\/co\/#organization\",\"name\":\"ABS Global Colombia\",\"url\":\"https:\/\/www-test.absglobal.com\/co\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www-test.absglobal.com\/co\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-test.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Colombia\"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/co\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Uruguay celebra la comercializaci\u00f3n de los primeros terneros Beef InFocus - ABS Global Colombia","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Uruguay celebra la comercializaci\u00f3n de los primeros terneros Beef InFocus","og_description":"Un a\u00f1o despu\u00e9s del lanzamiento de la tecnolog\u00eda innovadora de ABS, una asociaci\u00f3n con Berrutti United Breeders &amp; Packers ya muestra su potencial, dirigiendo a los terneros Beef InFocus NuEra a la cadena de producci\u00f3n de carne&nbsp; Las \u00faltimas semanas de 2020 trajeron algo nuevo que movi\u00f3 a ABS y consolid\u00f3 uno de sus productos [&hellip;]","og_url":"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/","og_site_name":"ABS Global Colombia","article_modified_time":"2021-01-20T17:24:11+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/www-test.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2021\/01\/WhatsApp-Image-2020-12-15-at-09.55.01.jpeg?fit=1600%2C1066","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/","url":"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/","name":"Uruguay celebra la comercializaci\u00f3n de los primeros terneros Beef InFocus - ABS Global Colombia","isPartOf":{"@id":"https:\/\/www-test.absglobal.com\/co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/#primaryimage"},"image":{"@id":"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/#primaryimage"},"thumbnailUrl":"https:\/\/www-test.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2021\/01\/WhatsApp-Image-2020-12-15-at-09.55.01.jpeg","datePublished":"2021-01-20T17:24:10+00:00","dateModified":"2021-01-20T17:24:11+00:00","breadcrumb":{"@id":"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/#primaryimage","url":"https:\/\/www-test.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2021\/01\/WhatsApp-Image-2020-12-15-at-09.55.01.jpeg","contentUrl":"https:\/\/www-test.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2021\/01\/WhatsApp-Image-2020-12-15-at-09.55.01.jpeg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/www-test.absglobal.com\/co\/articles\/uruguay-celebra-la-comercializacion-de-los-primeros-terneros-beef-infocus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-test.absglobal.com\/co\/"},{"@type":"ListItem","position":2,"name":"News Articles","item":"https:\/\/www-test.absglobal.com\/co\/articles\/"},{"@type":"ListItem","position":3,"name":"Uruguay celebra la comercializaci\u00f3n de los primeros terneros Beef InFocus"}]},{"@type":"WebSite","@id":"https:\/\/www-test.absglobal.com\/co\/#website","url":"https:\/\/www-test.absglobal.com\/co\/","name":"ABS Global Colombia","description":"","publisher":{"@id":"https:\/\/www-test.absglobal.com\/co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-test.absglobal.com\/co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www-test.absglobal.com\/co\/#organization","name":"ABS Global Colombia","url":"https:\/\/www-test.absglobal.com\/co\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www-test.absglobal.com\/co\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-test.absglobal.com\/co\/wp-content\/uploads\/sites\/18\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Colombia"},"image":{"@id":"https:\/\/www-test.absglobal.com\/co\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-test.absglobal.com\/co\/wp-json\/wp\/v2\/abs_news_article\/3445"}],"collection":[{"href":"https:\/\/www-test.absglobal.com\/co\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-test.absglobal.com\/co\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/co\/wp-json\/wp\/v2\/users\/342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/co\/wp-json\/wp\/v2\/media\/3446"}],"wp:attachment":[{"href":"https:\/\/www-test.absglobal.com\/co\/wp-json\/wp\/v2\/media?parent=3445"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/co\/wp-json\/wp\/v2\/abs_news_category?post=3445"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/co\/wp-json\/wp\/v2\/abs_news_tag?post=3445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}