{"id":3232,"date":"2020-05-15T10:19:02","date_gmt":"2020-05-15T15:19:02","guid":{"rendered":"https:\/\/www-test.absglobal.com\/cl\/?post_type=abs_news_article&#038;p=3232"},"modified":"2020-05-15T10:22:09","modified_gmt":"2020-05-15T15:22:09","slug":"abs-celebra-los-resultados-alcanzados-en-2019","status":"publish","type":"abs_news_article","link":"https:\/\/www-test.absglobal.com\/cl\/articles\/abs-celebra-los-resultados-alcanzados-en-2019\/","title":{"rendered":"ABS celebra los resultados alcanzados en 2019"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Con el lanzamiento de nuevos productos, la promoci\u00f3n de nuevos eventos y la consolidaci\u00f3n de la mejor gen\u00e9tica del mercado, la compa\u00f1\u00eda se prepara para seguir evolucionando en 2020<\/h2>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>ABS ha conseguido muchos \u00e9xitos que son motivo de celebraci\u00f3n a medida que comenzamos una nueva d\u00e9cada. En 2019, la compa\u00f1\u00eda estableci\u00f3 nuevos r\u00e9cords, lanz\u00f3 nuevos productos y tuvimos la oportunidad de compartir experiencias muy beneficiosas con la participaci\u00f3n de cientos de productores, junto con esto, seguimos siendo los pioneros en mejoramiento gen\u00e9tico, y nuestros clientes nos reconocen como la mejor gen\u00e9tica del mercado, convirti\u00e9ndonos en el principal aliado para miles de ganaderos en Am\u00e9rica Latina.<\/p>\n\n\n\n<p>\u201cCiertamente, fue otro a\u00f1o de desarrollo y crecimiento para la gen\u00e9tica bovina y la ganader\u00eda. ABS se enorgullece de ser parte de un movimiento que brinda mejoras gen\u00e9ticas y eficiencia a las granjas de carne y leche en toda Am\u00e9rica Latina, haciendo un amplio uso de la mejor tecnolog\u00eda disponible en el mercado\u201d, celebra el Director Regional de ABS Am\u00e9rica Latina, Ricardo Campos.<\/p>\n\n\n\n<p>Los hitos de este a\u00f1o 2019 han sido muchos. ABS lanz\u00f3 Beef InFocus en varios pa\u00edses, la tecnolog\u00eda beef on dairy l\u00edder en el mercado se agreg\u00f3 a la cartera diferenciada de ABS y result\u00f3 en un producto completo, que garantiza una fuente secundaria de ingresos para el productor lechero y contribuye a la inserci\u00f3n de productos de alta calidad en la cadena de producci\u00f3n de carne. La disponibilidad de esta tecnolog\u00eda fue uno de los momentos m\u00e1s notables de 2019 para las operaciones de ABS en Am\u00e9rica Latina, contribuyendo al aumento de la rentabilidad de los reba\u00f1os lecheros en varios pa\u00edses de la regi\u00f3n. Uruguay fue el pa\u00eds elegido para su lanzamiento, acontecimiento calificado como un gran suceso que cont\u00f3 con la presencia de varios productores y clientes ABS de Am\u00e9rica Latina<\/p>\n\n\n\n<p>En agosto, un grupo de 10 productores y t\u00e9cnicos uruguayos participaron de una gira por el sur de Chile, promovida por ABS. El itinerario del viaje incluy\u00f3 visitas a lecher\u00edas y otros lugares que representan el crecimiento del ganado chileno y el uso de la gen\u00e9tica al servicio del desarrollo, evidenciando la importancia de la tecnolog\u00eda ABS para el pa\u00eds. En noviembre ganaderos de Uruguay viajaron a Argentina, para visitar propiedades que utilizan nuestros productos para mejorar la gen\u00e9tica de los reba\u00f1os de carne. Esto en el marco del compartir conocimientos, gesti\u00f3n e ideas exitosas entre los pa\u00edses de la regi\u00f3n<\/p>\n\n\n\n<p>El laboratorio de embriones de ABS Brasil, impulsado por la tecnolog\u00eda IVB, que fue adquirida oficialmente el a\u00f1o pasado, rompi\u00f3 el r\u00e9cord de producci\u00f3n en su primer aniversario. En junio, se hab\u00edan producido m\u00e1s de 31,000 embriones: el promedio mensual oscila entre 7,000 y 9,000 embriones, todos los cuales tienen una gen\u00e9tica especialmente dise\u00f1ada para lograr resultados impactantes a un ritmo nunca visto.<\/p>\n\n\n\n<p>La demanda de embriones IVB Neo creci\u00f3 en m\u00e1s del 30%, y la l\u00ednea ABS Neo experiment\u00f3 un impresionante aumento de la demanda de un 266% respecto al a\u00f1o anterior. El resultado destaca no solo la aceptaci\u00f3n universal de la tecnolog\u00eda de embriones de ABS en el mercado, sino tambi\u00e9n la satisfacci\u00f3n de los productores que utilizaron estos productos en sus reba\u00f1os.<\/p>\n\n\n\n<p>En marzo, el equipo de ABS Am\u00e9rica Latina particip\u00f3 de la Conferencia del World Angus Secretariat, que present\u00f3 importantes discusiones sobre la cadena productiva de la carne uruguaya, en un a\u00f1o extremadamente relevante para el sector nacional. Uruguay es el 7\u00ba mayor exportador de carne de vacuno del mundo, con el 84% de su territorio nacional dedicado a la ganader\u00eda.<\/p>\n\n\n\n<p>En M\u00e9xico, ABS ha firmado una importante asociaci\u00f3n con el Instituto Tecnol\u00f3gico de Sonora (Itson), con el objetivo de aumentar la comercializaci\u00f3n de semen y embriones en la regi\u00f3n de la costa pac\u00edfica del pa\u00eds. Por medio del convenio, la gen\u00e9tica ABS ser\u00e1 utilizada en el reba\u00f1o lechero mantenido por la instituci\u00f3n de educaci\u00f3n superior. Adem\u00e1s, el equipo de profesionales y estudiantes del Itson, que trabaja con asistencia t\u00e9cnica reproductiva a los productores de carne y leche de la regi\u00f3n, incentivar\u00e1 el uso de las soluciones de mejoramiento ofrecidas por ABS.<\/p>\n\n\n\n<p>Grandes campa\u00f1as se llevaron a cabo en 2019. De particular inter\u00e9s es el movimiento \u201cNosotros Amamos la Leche\u201d, promovido por la compa\u00f1\u00eda para honrar la cadena de producci\u00f3n de este alimento tan esencial para Am\u00e9rica Latina y el mundo, enfatizando el papel de la gen\u00e9tica en su producci\u00f3n y contribuci\u00f3n a la misi\u00f3n de alimentar al planeta. Celebramos la d\u00e9cima edici\u00f3n del Tour T\u00e9cnico de Carne, m\u00e1s de 3.000 kil\u00f3metros recorridos, los estados de Mato Grosso, Paran\u00e1, Goi\u00e1s y Mato Grosso do Sul. Por segundo a\u00f1o consecutivo se desarroll\u00f3 \u201cABS Experience\u201d en la cual participaron m\u00e1s de 250 productores de 30 pa\u00edses, cinco d\u00edas en los Estados Unidos, para conocer de cerca lo mejor de la cadena lechera estadounidense. Por otra parte, un grupo de 60 ganaderos de toda Am\u00e9rica Latina participaron en otro \u201cBeef Tour USA\u201d, esta vez, para presenciar lo mejor de la cadena de producci\u00f3n de carne estadounidense, todo impregnado por la gen\u00e9tica y la tecnolog\u00eda ABS.<\/p>\n\n\n\n<p>La primera edici\u00f3n del \u201cABS Day\u201d, se desarroll\u00f3 con mucho \u00e9xito y aceptaci\u00f3n, donde productores y clientes de todo Brasil se reunieron en Fazenda Cobi\u00e7a, en Tr\u00eas Cora\u00e7\u00f5es, Minas Gerais, para conocer los impresionantes resultados logrados por el equipo despu\u00e9s de grandes inversiones en soluciones gen\u00e9ticas.<\/p>\n\n\n\n<p>Innovadores cat\u00e1logos fueron lanzados por la compa\u00f1\u00eda durante el a\u00f1o, con informaci\u00f3n relevante en el avance de las tecnol\u00f3gicas gen\u00e9ticas para todas las razas, el cat\u00e1logo Carne Europea ha entregado noticias sorprendentes a los productores interesados en invertir en sistemas de cruzamiento industrial, ofreciendo los mejores toros para la m\u00e1xima eficiencia y para consolidar el progreso gen\u00e9tico de las granjas.<\/p>\n\n\n\n<p>Sin lugar a duda el a\u00f1o 2019 ha sido un a\u00f1o muy gratificante, marcado por el crecimiento, la tecnolog\u00eda y la satisfacci\u00f3n de los clientes de toda Am\u00e9rica Latina. As\u00ed es como ABS est\u00e1 contribuyendo al cambio sustentable del mundo del ganado, contribuyendo con la mejor gen\u00e9tica existente, mejorando los reba\u00f1os de todas las razas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el lanzamiento de nuevos productos, la promoci\u00f3n de nuevos eventos y la consolidaci\u00f3n de la mejor gen\u00e9tica del mercado, la compa\u00f1\u00eda se prepara para seguir evolucionando en 2020 ABS ha conseguido muchos \u00e9xitos que son motivo de celebraci\u00f3n a medida que comenzamos una nueva d\u00e9cada. En 2019, la compa\u00f1\u00eda estableci\u00f3 nuevos r\u00e9cords, lanz\u00f3 nuevos [&hellip;]<\/p>\n","protected":false},"author":289,"featured_media":0,"template":"","abs_news_category":[102],"abs_news_tag":[106,104],"class_list":["post-3232","abs_news_article","type-abs_news_article","status-publish","hentry","abs_news_category-noticias","abs_news_tag-carne","abs_news_tag-leche","ep_custom_result-carne","ep_custom_result-leche"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ABS celebra los resultados alcanzados en 2019 - ABS Global Chile<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABS celebra los resultados alcanzados en 2019\" \/>\n<meta property=\"og:description\" content=\"Con el lanzamiento de nuevos productos, la promoci\u00f3n de nuevos eventos y la consolidaci\u00f3n de la mejor gen\u00e9tica del mercado, la compa\u00f1\u00eda se prepara para seguir evolucionando en 2020 ABS ha conseguido muchos \u00e9xitos que son motivo de celebraci\u00f3n a medida que comenzamos una nueva d\u00e9cada. En 2019, la compa\u00f1\u00eda estableci\u00f3 nuevos r\u00e9cords, lanz\u00f3 nuevos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-test.absglobal.com\/cl\/articles\/abs-celebra-los-resultados-alcanzados-en-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Chile\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-15T15:22:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-test.absglobal.com\/cl\/articles\/abs-celebra-los-resultados-alcanzados-en-2019\/\",\"url\":\"https:\/\/www-test.absglobal.com\/cl\/articles\/abs-celebra-los-resultados-alcanzados-en-2019\/\",\"name\":\"ABS celebra los resultados alcanzados en 2019 - ABS Global Chile\",\"isPartOf\":{\"@id\":\"https:\/\/www-test.absglobal.com\/cl\/#website\"},\"datePublished\":\"2020-05-15T15:19:02+00:00\",\"dateModified\":\"2020-05-15T15:22:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-test.absglobal.com\/cl\/articles\/abs-celebra-los-resultados-alcanzados-en-2019\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-test.absglobal.com\/cl\/articles\/abs-celebra-los-resultados-alcanzados-en-2019\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-test.absglobal.com\/cl\/articles\/abs-celebra-los-resultados-alcanzados-en-2019\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-test.absglobal.com\/cl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News Articles\",\"item\":\"https:\/\/www-test.absglobal.com\/cl\/articles\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ABS celebra los resultados alcanzados en 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-test.absglobal.com\/cl\/#website\",\"url\":\"https:\/\/www-test.absglobal.com\/cl\/\",\"name\":\"ABS Global Chile\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-test.absglobal.com\/cl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-test.absglobal.com\/cl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-test.absglobal.com\/cl\/#organization\",\"name\":\"ABS Global Chile\",\"url\":\"https:\/\/www-test.absglobal.com\/cl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www-test.absglobal.com\/cl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-test.absglobal.com\/cl\/wp-content\/uploads\/sites\/15\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/cl\/wp-content\/uploads\/sites\/15\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Chile\"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/cl\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ABS celebra los resultados alcanzados en 2019 - ABS Global Chile","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_MX","og_type":"article","og_title":"ABS celebra los resultados alcanzados en 2019","og_description":"Con el lanzamiento de nuevos productos, la promoci\u00f3n de nuevos eventos y la consolidaci\u00f3n de la mejor gen\u00e9tica del mercado, la compa\u00f1\u00eda se prepara para seguir evolucionando en 2020 ABS ha conseguido muchos \u00e9xitos que son motivo de celebraci\u00f3n a medida que comenzamos una nueva d\u00e9cada. En 2019, la compa\u00f1\u00eda estableci\u00f3 nuevos r\u00e9cords, lanz\u00f3 nuevos [&hellip;]","og_url":"https:\/\/www-test.absglobal.com\/cl\/articles\/abs-celebra-los-resultados-alcanzados-en-2019\/","og_site_name":"ABS Global Chile","article_modified_time":"2020-05-15T15:22:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-test.absglobal.com\/cl\/articles\/abs-celebra-los-resultados-alcanzados-en-2019\/","url":"https:\/\/www-test.absglobal.com\/cl\/articles\/abs-celebra-los-resultados-alcanzados-en-2019\/","name":"ABS celebra los resultados alcanzados en 2019 - ABS Global Chile","isPartOf":{"@id":"https:\/\/www-test.absglobal.com\/cl\/#website"},"datePublished":"2020-05-15T15:19:02+00:00","dateModified":"2020-05-15T15:22:09+00:00","breadcrumb":{"@id":"https:\/\/www-test.absglobal.com\/cl\/articles\/abs-celebra-los-resultados-alcanzados-en-2019\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-test.absglobal.com\/cl\/articles\/abs-celebra-los-resultados-alcanzados-en-2019\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www-test.absglobal.com\/cl\/articles\/abs-celebra-los-resultados-alcanzados-en-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-test.absglobal.com\/cl\/"},{"@type":"ListItem","position":2,"name":"News Articles","item":"https:\/\/www-test.absglobal.com\/cl\/articles\/"},{"@type":"ListItem","position":3,"name":"ABS celebra los resultados alcanzados en 2019"}]},{"@type":"WebSite","@id":"https:\/\/www-test.absglobal.com\/cl\/#website","url":"https:\/\/www-test.absglobal.com\/cl\/","name":"ABS Global Chile","description":"","publisher":{"@id":"https:\/\/www-test.absglobal.com\/cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-test.absglobal.com\/cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www-test.absglobal.com\/cl\/#organization","name":"ABS Global Chile","url":"https:\/\/www-test.absglobal.com\/cl\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www-test.absglobal.com\/cl\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.absglobal.com\/cl\/wp-content\/uploads\/sites\/15\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-test.absglobal.com\/cl\/wp-content\/uploads\/sites\/15\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Chile"},"image":{"@id":"https:\/\/www-test.absglobal.com\/cl\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-test.absglobal.com\/cl\/wp-json\/wp\/v2\/abs_news_article\/3232"}],"collection":[{"href":"https:\/\/www-test.absglobal.com\/cl\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-test.absglobal.com\/cl\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/cl\/wp-json\/wp\/v2\/users\/289"}],"wp:attachment":[{"href":"https:\/\/www-test.absglobal.com\/cl\/wp-json\/wp\/v2\/media?parent=3232"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/cl\/wp-json\/wp\/v2\/abs_news_category?post=3232"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/cl\/wp-json\/wp\/v2\/abs_news_tag?post=3232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}