{"id":2855,"date":"2020-03-29T23:41:00","date_gmt":"2020-03-30T04:41:00","guid":{"rendered":"http:\/\/www-test.absglobal.com\/br\/?post_type=abs_service&#038;p=2855"},"modified":"2020-04-05T22:33:52","modified_gmt":"2020-04-06T03:33:52","slug":"boviflag","status":"publish","type":"abs_service","link":"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/","title":{"rendered":"Boviflag"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Melhore sua taxa de servi\u00e7o. Adesivo auxiliar na detec\u00e7\u00e3o de cio.<\/h2>\n\n\n\n<p>A detec\u00e7\u00e3o de cio \u00e9 o primeiro passo para se conseguir bons resultados reprodutivos. Aumentar essa efici\u00eancia \u00e9 uma das maiores dificuldades das rotinas das fazendas. Para facilitar a identifica\u00e7\u00e3o do cio, o Boviflag \u00e9 um grande aliado dos produtores rurais.<\/p>\n\n\n\n<p>O Boviflag \u00e9 um&nbsp;adesivo autocolante que auxilia o produtor na identifica\u00e7\u00e3o do cio. A ferramenta \u00e9 produzida pela BoviTime, uma empresa da \u00c1frica do Sul, e revendida pela ABS com exclusividade no Brasil.<\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"240\" height=\"29\" src=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/04\/boviflag.png\" alt=\"\" class=\"wp-image-2859\"\/><\/figure><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\t<section id=\"\" class=\" section-wrapper section-wrapper-fluid section-wrapper-banner\" data-magellan-target=\"\">\n\t\t<div class=\"section-wrapper-background\" style=\"background-image: url('https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/04\/00-Boviflag.jpg');\"><\/div>\n\t\t<div class=\"section-wrapper-overlay\"><\/div>\n\t\t<div class=\"section-wrapper-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-container\">\n\t\t\t\t\t\t<div class=\"grid-x align-left\">\n\t\t\t\t\t\t\t<div class=\"cell medium-7 \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"section-content\">\n\t\t\t\t\t\t\t\t\t\t<p>Compre o Boviflag pela loja virtual e receba em casa.<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/loja.abspecplan.com.br\/loja\/produtos\/455\" class=\"button\">Visita a Loja ABS<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\t\n\n\n<h2 class=\"wp-block-heading\">Como funciona?<\/h2>\n\n\n\n<p>O adesivo Boviflag \u00e9 colado pr\u00f3ximo a base da cauda da vaca. Quando a f\u00eamea que estiver no cio for montada, o adesivo muda de cor. Assim, a orienta\u00e7\u00e3o \u00e9 que, diariamente, o Boviflag seja observado durante a rotina da fazenda.<\/p>\n\n\n\n<p>Vale destacar que o BoviFlag pode ser utilizado em vacas e novilhas, tanto em rebanhos de corte, como em rebanhos leiteiros. <\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/04\/ABS-Boviflag.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Manual do Boviflag &#8211; Utiliza\u00e7\u00e3o no Leite e no Corte<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Boviflag: o bra\u00e7o direito do produtor na detec\u00e7\u00e3o de cio\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/zYqWNotYvW0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Palavra de quem usa<\/h2>\n\n\n\n<p>Cada vez mais produtores conhecem os benef\u00edcios do Boviflag. Uma ferramenta extremamente simples que garante os resultados. Veja, nas palavras de clientes ABS que apostaram no produto, como o Boviflag pode contribuir para aumentar a taxa de servi\u00e7o do rebanho:<\/p>\n\n\n\n<div class=\"wp-block-columns alignfull is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-pullquote is-style-default\"><blockquote><p>\u201cA gente sentiu a melhora quando come\u00e7amos a usar o BOViFLAG nos animais protocolados. Em todos os animais, depois de 14 dias da IAFT, colocamos o adesivo. Isso trouxe um aumento significante na nossa observa\u00e7\u00e3o de cio de retorno. Eu acredito que seja esse fator que determinou o aumento da nossa taxa de servi\u00e7o.\u201d<\/p><cite>Tiago Nogueira Di\u00f3genes<br>M\u00e9dico veterin\u00e1rio da fazenda S\u00e3o Jos\u00e9, em Limoeira do Norte (CE), onde a taxa de servi\u00e7o cresceu de 50% para 65 a 70%.<\/cite><\/blockquote><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-pullquote is-style-default\"><blockquote><p>\u201cAdotamos a pr\u00e1tica de colocar o adesivo na vaca uma semana ap\u00f3s a insemina\u00e7\u00e3o. Isso nos permitiu uma boa organiza\u00e7\u00e3o de cada animal individual. Fechamos o ano passado com uma taxa de prenhez nas vacas confinadas de 22%, e a taxa de servi\u00e7o cresceu 17% desde que come\u00e7amos a usar o adesivo.\u201d<\/p><cite>Giovanni Nochi<br>Gerente da Agropecu\u00e1ria Palma, em Luzi\u00e2nia (GO).<\/cite><\/blockquote><\/figure>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Boviflag: como funciona?\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/rTbeiw6Pz2Q?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\t<section id=\"repFinder\" class=\"alignfull rep-finder\" data-magellan-target=\"repFinder\">\n\t\t<div class=\"section-wrapper\">\n\t\t\t\t\t\t\t<h2 class=\"section-title\">Encontre seu Representante ABS<\/h2>\n\t\t\t\n\t\t\t<div class=\"grid-x grid-margin-x align-justify rep-finder-inner\">\n\t\t\t\t<div class=\"cell medium-large-6\">\n\t\t\t\t\t<button class=\"button rep-finder-cta\" id=\"selectRep\" data-open=\"repFinderModal\">Encontre Seu Representante<\/button>\n\t\t\t\t\t<div class=\"rep-finder-selected-rep\" id=\"selectedRep\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"cell medium-large-6\">\n\t\t\t\t\t\t<h4>D\u00favidas gerais<\/h4>\n\t\t\t\t\t\t<hr class=\"rep-finder-divider\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"rep-finder-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><a href=\"tel:(34) 3319-5400\"><h5><img decoding=\"async\" src=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/themes\/abs\/dist\/assets\/img\/icons\/phone-icon.svg\" alt=\"Phone icon\"> (34) 3319-5400<\/h5><\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/section>\n\t","protected":false},"excerpt":{"rendered":"<p>Melhore sua taxa de servi\u00e7o. Adesivo auxiliar na detec\u00e7\u00e3o de cio. A detec\u00e7\u00e3o de cio \u00e9 o primeiro passo para se conseguir bons resultados reprodutivos. Aumentar essa efici\u00eancia \u00e9 uma das maiores dificuldades das rotinas das fazendas. Para facilitar a identifica\u00e7\u00e3o do cio, o Boviflag \u00e9 um grande aliado dos produtores rurais. O Boviflag \u00e9 [&hellip;]<\/p>\n","protected":false},"author":289,"featured_media":2857,"template":"","categories":[],"abs_type":[62],"class_list":["post-2855","abs_service","type-abs_service","status-publish","has-post-thumbnail","hentry","abs_type-product"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Boviflag - ABS Global Brasil<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boviflag\" \/>\n<meta property=\"og:description\" content=\"Melhore sua taxa de servi\u00e7o. Adesivo auxiliar na detec\u00e7\u00e3o de cio. A detec\u00e7\u00e3o de cio \u00e9 o primeiro passo para se conseguir bons resultados reprodutivos. Aumentar essa efici\u00eancia \u00e9 uma das maiores dificuldades das rotinas das fazendas. Para facilitar a identifica\u00e7\u00e3o do cio, o Boviflag \u00e9 um grande aliado dos produtores rurais. O Boviflag \u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-06T03:33:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/04\/00-Boviflag.jpg?fit=800%2C533\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/\",\"name\":\"Boviflag - ABS Global Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/04\/00-Boviflag.jpg\",\"datePublished\":\"2020-03-30T04:41:00+00:00\",\"dateModified\":\"2020-04-06T03:33:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/#primaryimage\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/04\/00-Boviflag.jpg\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/04\/00-Boviflag.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos e Servi\u00e7os\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/solucoes\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Boviflag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"name\":\"ABS Global Brasil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\",\"name\":\"ABS Global Brasil\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Brasil \"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Boviflag - ABS Global Brasil","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Boviflag","og_description":"Melhore sua taxa de servi\u00e7o. Adesivo auxiliar na detec\u00e7\u00e3o de cio. A detec\u00e7\u00e3o de cio \u00e9 o primeiro passo para se conseguir bons resultados reprodutivos. Aumentar essa efici\u00eancia \u00e9 uma das maiores dificuldades das rotinas das fazendas. Para facilitar a identifica\u00e7\u00e3o do cio, o Boviflag \u00e9 um grande aliado dos produtores rurais. O Boviflag \u00e9 [&hellip;]","og_url":"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/","og_site_name":"ABS Global Brasil","article_modified_time":"2020-04-06T03:33:52+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/04\/00-Boviflag.jpg?fit=800%2C533","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/","url":"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/","name":"Boviflag - ABS Global Brasil","isPartOf":{"@id":"https:\/\/www-test.absglobal.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/#primaryimage"},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/#primaryimage"},"thumbnailUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/04\/00-Boviflag.jpg","datePublished":"2020-03-30T04:41:00+00:00","dateModified":"2020-04-06T03:33:52+00:00","breadcrumb":{"@id":"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/#primaryimage","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/04\/00-Boviflag.jpg","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/04\/00-Boviflag.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www-test.absglobal.com\/br\/solucoes\/boviflag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-test.absglobal.com\/br\/"},{"@type":"ListItem","position":2,"name":"Produtos e Servi\u00e7os","item":"https:\/\/www-test.absglobal.com\/br\/solucoes\/"},{"@type":"ListItem","position":3,"name":"Boviflag"}]},{"@type":"WebSite","@id":"https:\/\/www-test.absglobal.com\/br\/#website","url":"https:\/\/www-test.absglobal.com\/br\/","name":"ABS Global Brasil","description":"","publisher":{"@id":"https:\/\/www-test.absglobal.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www-test.absglobal.com\/br\/#organization","name":"ABS Global Brasil","url":"https:\/\/www-test.absglobal.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Brasil "},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_service\/2855"}],"collection":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_service"}],"about":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/types\/abs_service"}],"author":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/users\/289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media\/2857"}],"wp:attachment":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media?parent=2855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/categories?post=2855"},{"taxonomy":"abs_type","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_type?post=2855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}