{"id":7906,"date":"2023-12-28T16:03:22","date_gmt":"2023-12-28T21:03:22","guid":{"rendered":"https:\/\/www-test.absglobal.com\/br\/?post_type=abs_news_article&#038;p=7906"},"modified":"2023-12-28T16:03:24","modified_gmt":"2023-12-28T21:03:24","slug":"retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios","status":"publish","type":"abs_news_article","link":"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/","title":{"rendered":"Retrospectiva 2023: Produtores de carne e leite avan\u00e7aram, mesmo em ano marcado por grandes desafios"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" height=\"683\" width=\"1024\" src=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Corte.jpg?w=1024\" alt=\"\" class=\"wp-image-7907\" srcset=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Corte.jpg 6000w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Corte.jpg?resize=300,200 300w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Corte.jpg?resize=768,512 768w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Corte.jpg?resize=1024,683 1024w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Corte.jpg?resize=1536,1024 1536w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Corte.jpg?resize=2048,1365 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O ano de 2023 foi marcado por grandes desafios para o setor produtivo de carne e leite. O cen\u00e1rio de baixa no mercado derrubou o pre\u00e7o do boi gordo, diminuindo margens dos pecuaristas de corte em todo o pa\u00eds. Na pecu\u00e1ria leiteira, as importa\u00e7\u00f5es do Mercosul geraram queda nos pre\u00e7os pagos aos produtores. Mesmo com tantas dificuldades, o pecuarista n\u00e3o deixou de produzir e de investir em gen\u00e9tica de qualidade.<\/p>\n\n\n\n<p>Nesse contexto, a ABS, empresa l\u00edder em fornecimento de gen\u00e9tica bovina, apresentou novas solu\u00e7\u00f5es ao longo deste ano, permitindo acelerar cada vez mais o progresso gen\u00e9tico dos rebanhos. \u201cBuscamos demonstrar e validar os impactos financeiros da gen\u00e9tica para nosso cliente. Oferecemos grandes produtos e tecnologias com resultados comprovados, protegendo nosso cliente para que ele pudesse tomar decis\u00f5es racionais em rela\u00e7\u00e3o ao manejo gen\u00e9tico da propriedade\u201d, destaca o Diretor Geral da ABS Brasil, M\u00e1rcio Nery, avisando que a expectativa \u00e9 de mudan\u00e7a de cen\u00e1rio no pr\u00f3ximo ano. \u201cTemos expectativa muito positiva para 2024, com uma invers\u00e3o do ciclo pecu\u00e1rio, demandando animais terminados, bezerros desmamados, com qualidade gen\u00e9tica. E tamb\u00e9m uma demanda crescente do cruzamento industrial\u201d, completa.<\/p>\n\n\n\n<p>E por falar nisso, entre os destaques, a Super Dose ABS se consolidou como o mais eficiente e lucrativo produto para o cruzamento industrial, com demonstra\u00e7\u00f5es a campo, abates com avalia\u00e7\u00e3o de carca\u00e7a e qualidade de carne. A Super Dose \u00e9 validada por dados de animais F1, produzidos e testados no Brasil. \u201cUm volume expressivo que nos permite entregar aos produtores informa\u00e7\u00f5es relevantes, de alto impacto econ\u00f4mico para o sistema de produ\u00e7\u00e3o de cruzamento industrial com termina\u00e7\u00e3o intensiva. O que a solu\u00e7\u00e3o est\u00e1 proporcionando ao nosso cliente s\u00e3o animais com maior ganho di\u00e1rio no confinamento, maior peso de carca\u00e7a e efici\u00eancia alimentar\u201d, ressalta o Gerente de Produto e Projetos Corte Europeu da ABS, Marcelo Selistre.<\/p>\n\n\n\n<p>No Sexcel, a gen\u00e9tica sexada da ABS, a novidade foi o Sexcel Macho, tecnologia que aumenta o nascimento de bezerros machos, com maior ganho de peso, aumentando a lucratividade dentro da propriedade. \u201cUma ferramenta pontual para o produtor que busca aumentar a produtividade de quilos de bezerro desmamado por matrizes, al\u00e9m da lucratividade, j\u00e1 que as matrizes v\u00e3o desmamar maior n\u00famero de machos, agregando valor ao quilo de bezerro\u201d, afirma o Gerente de Mercado e Contas-Chave Corte da ABS, Gustavo Morales.<\/p>\n\n\n\n<p>Destaque tamb\u00e9m para a linha NEO de embri\u00f5es ABS, que avan\u00e7a para levar um produto cada vez melhor ao pecuarista. \u201cEsperamos uma melhoria do mercado de leite, com nossa capacidade de produzir mais com menos. Podemos esperar tamb\u00e9m novidades tecnol\u00f3gicas no setor de embri\u00f5es, a ABS vir\u00e1 com novidades na linha ABS NEO. Ent\u00e3o nosso cliente pode ter certeza que vamos continuar trabalhando para levar gen\u00e9tica de qualidade, demonstrando o impacto financeiro dessas decis\u00f5es gen\u00e9ticas. A gente n\u00e3o pode esquecer do custo da gen\u00e9tica dentro da produ\u00e7\u00e3o, de um litro de leite, de um arroba de carne, \u00e9 o menor custo, que faz grande diferen\u00e7a\u201d, finaliza M\u00e1rcio Nery.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" height=\"739\" width=\"1024\" src=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Leite...jpg?w=1024\" alt=\"\" class=\"wp-image-7908\" srcset=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Leite...jpg 6205w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Leite...jpg?resize=300,217 300w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Leite...jpg?resize=768,554 768w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Leite...jpg?resize=1024,739 1024w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Leite...jpg?resize=1536,1109 1536w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Leite...jpg?resize=2048,1479 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O ano de 2023 foi marcado por grandes desafios para o setor produtivo de carne e leite. O cen\u00e1rio de baixa no mercado derrubou o pre\u00e7o do boi gordo, diminuindo margens dos pecuaristas de corte em todo o pa\u00eds. Na pecu\u00e1ria leiteira, as importa\u00e7\u00f5es do Mercosul geraram queda nos pre\u00e7os pagos aos produtores. Mesmo com [&hellip;]<\/p>\n","protected":false},"author":10336,"featured_media":0,"template":"","abs_news_category":[],"abs_news_tag":[],"class_list":["post-7906","abs_news_article","type-abs_news_article","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Retrospectiva 2023: Produtores de carne e leite avan\u00e7aram, mesmo em ano marcado por grandes desafios - ABS Global Brasil<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retrospectiva 2023: Produtores de carne e leite avan\u00e7aram, mesmo em ano marcado por grandes desafios\" \/>\n<meta property=\"og:description\" content=\"O ano de 2023 foi marcado por grandes desafios para o setor produtivo de carne e leite. O cen\u00e1rio de baixa no mercado derrubou o pre\u00e7o do boi gordo, diminuindo margens dos pecuaristas de corte em todo o pa\u00eds. Na pecu\u00e1ria leiteira, as importa\u00e7\u00f5es do Mercosul geraram queda nos pre\u00e7os pagos aos produtores. Mesmo com [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-28T21:03:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Corte.jpg?w=1024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/\",\"name\":\"Retrospectiva 2023: Produtores de carne e leite avan\u00e7aram, mesmo em ano marcado por grandes desafios - ABS Global Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Corte.jpg?w=1024\",\"datePublished\":\"2023-12-28T21:03:22+00:00\",\"dateModified\":\"2023-12-28T21:03:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/#primaryimage\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Corte.jpg\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Corte.jpg\",\"width\":6000,\"height\":4000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Retrospectiva 2023: Produtores de carne e leite avan\u00e7aram, mesmo em ano marcado por grandes desafios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"name\":\"ABS Global Brasil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\",\"name\":\"ABS Global Brasil\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Brasil \"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Retrospectiva 2023: Produtores de carne e leite avan\u00e7aram, mesmo em ano marcado por grandes desafios - ABS Global Brasil","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Retrospectiva 2023: Produtores de carne e leite avan\u00e7aram, mesmo em ano marcado por grandes desafios","og_description":"O ano de 2023 foi marcado por grandes desafios para o setor produtivo de carne e leite. O cen\u00e1rio de baixa no mercado derrubou o pre\u00e7o do boi gordo, diminuindo margens dos pecuaristas de corte em todo o pa\u00eds. Na pecu\u00e1ria leiteira, as importa\u00e7\u00f5es do Mercosul geraram queda nos pre\u00e7os pagos aos produtores. Mesmo com [&hellip;]","og_url":"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/","og_site_name":"ABS Global Brasil","article_modified_time":"2023-12-28T21:03:24+00:00","og_image":[{"url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Corte.jpg?w=1024","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/","url":"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/","name":"Retrospectiva 2023: Produtores de carne e leite avan\u00e7aram, mesmo em ano marcado por grandes desafios - ABS Global Brasil","isPartOf":{"@id":"https:\/\/www-test.absglobal.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/#primaryimage"},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/#primaryimage"},"thumbnailUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Corte.jpg?w=1024","datePublished":"2023-12-28T21:03:22+00:00","dateModified":"2023-12-28T21:03:24+00:00","breadcrumb":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/#primaryimage","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Corte.jpg","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Corte.jpg","width":6000,"height":4000},{"@type":"BreadcrumbList","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/retrospectiva-2023-produtores-de-carne-e-leite-avancaram-mesmo-em-ano-marcado-por-grandes-desafios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-test.absglobal.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www-test.absglobal.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Retrospectiva 2023: Produtores de carne e leite avan\u00e7aram, mesmo em ano marcado por grandes desafios"}]},{"@type":"WebSite","@id":"https:\/\/www-test.absglobal.com\/br\/#website","url":"https:\/\/www-test.absglobal.com\/br\/","name":"ABS Global Brasil","description":"","publisher":{"@id":"https:\/\/www-test.absglobal.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www-test.absglobal.com\/br\/#organization","name":"ABS Global Brasil","url":"https:\/\/www-test.absglobal.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Brasil "},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article\/7906"}],"collection":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/users\/10336"}],"wp:attachment":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media?parent=7906"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_category?post=7906"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_tag?post=7906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}