{"id":7586,"date":"2023-12-12T15:11:15","date_gmt":"2023-12-12T20:11:15","guid":{"rendered":"https:\/\/www-test.absglobal.com\/br\/?post_type=abs_news_article&#038;p=7586"},"modified":"2023-12-12T15:11:17","modified_gmt":"2023-12-12T20:11:17","slug":"morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro","status":"publish","type":"abs_news_article","link":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/","title":{"rendered":"Morre touro Fabuloso, um dos mais importantes reprodutores da ra\u00e7a Gir Leiteiro"},"content":{"rendered":"\n<p><em>Ao longo da carreira, Fabuloso produziu mais de 50 mil doses de s\u00eamen e contribuiu com rebanhos de mais de 10 pa\u00edses diferentes<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" height=\"682\" width=\"1024\" src=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Fabuloso-do-Basa.jpg?w=1024\" alt=\"\" class=\"wp-image-7587\" srcset=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Fabuloso-do-Basa.jpg 2000w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Fabuloso-do-Basa.jpg?resize=300,200 300w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Fabuloso-do-Basa.jpg?resize=768,512 768w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Fabuloso-do-Basa.jpg?resize=1024,682 1024w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Fabuloso-do-Basa.jpg?resize=1536,1024 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A pecu\u00e1ria leiteira nacional perdeu nesta ter\u00e7a-feira (12), um de seus mais importantes touros da ra\u00e7a Gir Leiteiro. Fabuloso do BASA produziu mais de 50 mil doses de s\u00eamen convencional, mais de 3.000 doses de s\u00eamen sexado, e contribuiu com rebanhos de mais de 10 pa\u00edses diferentes. O reprodutor iniciou sua vida ainda muito jovem na Central ABS, em 2011, e se aposentou no ano passado, retornando \u00e0 Fazendas do BASA, em Leopoldina (MG).<\/p>\n\n\n\n<p>Filho do Teatro da Silv\u00e2nia na Faf\u00e1, Fabuloso explodiu em vendas ap\u00f3s a divulga\u00e7\u00e3o do teste de prog\u00eanie que comprovou todo seu potencial de transmiss\u00e3o de leite, com PTAL de 570 kg. \u201cFoi o primeiro touro provado de uma das mais importantes sele\u00e7\u00f5es de Gir Leiteiro, a Fazendas do BASA. Al\u00e9m da capacidade de transmiss\u00e3o de leite, Fabuloso conduzia outras caracter\u00edsticas importantes, como elevada transmiss\u00e3o de s\u00f3lidos, antecipando a idade ao primeiro parto, e filhas com excelente temperamento e qualidade de \u00fabere\u201d, destaca o Coordenador de Produto e Atendimento ao Cliente Leite da ABS, Fernando Rosa.<\/p>\n\n\n\n<p>Fabuloso ainda \u00e9 largamente utilizado na multiplica\u00e7\u00e3o por meio de embri\u00f5es, aumentando sua produ\u00e7\u00e3o de filhos. \u201cSua gen\u00e9tica ainda tem sido bastante procurada por sua genealogia, que permite evitar consanguinidade com outras linhagens bastante utilizadas, e ainda proporcionando muita capacidade de transmiss\u00e3o de leite. Nas centrais de insemina\u00e7\u00e3o, j\u00e1 existem filhos do Fabuloso em coleta de s\u00eamen e em teste de prog\u00eanie, al\u00e9m de milhares de filhas em destaque de produ\u00e7\u00e3o, tanto em rebanhos puros da ra\u00e7a Gir Leiteiro, como em rebanhos comerciais\u201d, completa Fernando Rosa.<\/p>\n\n\n\n<p>Nossa homenagem ao grande ra\u00e7ador Gir Leiteiro, Fabuloso do BASA!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao longo da carreira, Fabuloso produziu mais de 50 mil doses de s\u00eamen e contribuiu com rebanhos de mais de 10 pa\u00edses diferentes A pecu\u00e1ria leiteira nacional perdeu nesta ter\u00e7a-feira (12), um de seus mais importantes touros da ra\u00e7a Gir Leiteiro. Fabuloso do BASA produziu mais de 50 mil doses de s\u00eamen convencional, mais de [&hellip;]<\/p>\n","protected":false},"author":10336,"featured_media":0,"template":"","abs_news_category":[],"abs_news_tag":[],"class_list":["post-7586","abs_news_article","type-abs_news_article","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Morre touro Fabuloso, um dos mais importantes reprodutores da ra\u00e7a Gir Leiteiro - ABS Global Brasil<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Morre touro Fabuloso, um dos mais importantes reprodutores da ra\u00e7a Gir Leiteiro\" \/>\n<meta property=\"og:description\" content=\"Ao longo da carreira, Fabuloso produziu mais de 50 mil doses de s\u00eamen e contribuiu com rebanhos de mais de 10 pa\u00edses diferentes A pecu\u00e1ria leiteira nacional perdeu nesta ter\u00e7a-feira (12), um de seus mais importantes touros da ra\u00e7a Gir Leiteiro. Fabuloso do BASA produziu mais de 50 mil doses de s\u00eamen convencional, mais de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-12T20:11:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Fabuloso-do-Basa.jpg?w=1024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/\",\"name\":\"Morre touro Fabuloso, um dos mais importantes reprodutores da ra\u00e7a Gir Leiteiro - ABS Global Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Fabuloso-do-Basa.jpg?w=1024\",\"datePublished\":\"2023-12-12T20:11:15+00:00\",\"dateModified\":\"2023-12-12T20:11:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/#primaryimage\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Fabuloso-do-Basa.jpg\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Fabuloso-do-Basa.jpg\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Morre touro Fabuloso, um dos mais importantes reprodutores da ra\u00e7a Gir Leiteiro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"name\":\"ABS Global Brasil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\",\"name\":\"ABS Global Brasil\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Brasil \"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Morre touro Fabuloso, um dos mais importantes reprodutores da ra\u00e7a Gir Leiteiro - ABS Global Brasil","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Morre touro Fabuloso, um dos mais importantes reprodutores da ra\u00e7a Gir Leiteiro","og_description":"Ao longo da carreira, Fabuloso produziu mais de 50 mil doses de s\u00eamen e contribuiu com rebanhos de mais de 10 pa\u00edses diferentes A pecu\u00e1ria leiteira nacional perdeu nesta ter\u00e7a-feira (12), um de seus mais importantes touros da ra\u00e7a Gir Leiteiro. Fabuloso do BASA produziu mais de 50 mil doses de s\u00eamen convencional, mais de [&hellip;]","og_url":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/","og_site_name":"ABS Global Brasil","article_modified_time":"2023-12-12T20:11:17+00:00","og_image":[{"url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Fabuloso-do-Basa.jpg?w=1024","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/","url":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/","name":"Morre touro Fabuloso, um dos mais importantes reprodutores da ra\u00e7a Gir Leiteiro - ABS Global Brasil","isPartOf":{"@id":"https:\/\/www-test.absglobal.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/#primaryimage"},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/#primaryimage"},"thumbnailUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Fabuloso-do-Basa.jpg?w=1024","datePublished":"2023-12-12T20:11:15+00:00","dateModified":"2023-12-12T20:11:17+00:00","breadcrumb":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/#primaryimage","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Fabuloso-do-Basa.jpg","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/12\/Fabuloso-do-Basa.jpg","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-touro-fabuloso-um-dos-mais-importantes-reprodutores-da-raca-gir-leiteiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-test.absglobal.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www-test.absglobal.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Morre touro Fabuloso, um dos mais importantes reprodutores da ra\u00e7a Gir Leiteiro"}]},{"@type":"WebSite","@id":"https:\/\/www-test.absglobal.com\/br\/#website","url":"https:\/\/www-test.absglobal.com\/br\/","name":"ABS Global Brasil","description":"","publisher":{"@id":"https:\/\/www-test.absglobal.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www-test.absglobal.com\/br\/#organization","name":"ABS Global Brasil","url":"https:\/\/www-test.absglobal.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Brasil "},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article\/7586"}],"collection":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/users\/10336"}],"wp:attachment":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media?parent=7586"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_category?post=7586"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_tag?post=7586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}