{"id":7455,"date":"2023-11-09T07:06:30","date_gmt":"2023-11-09T12:06:30","guid":{"rendered":"https:\/\/www-test.absglobal.com\/br\/?post_type=abs_news_article&#038;p=7455"},"modified":"2023-11-09T07:06:31","modified_gmt":"2023-11-09T12:06:31","slug":"representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos","status":"publish","type":"abs_news_article","link":"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/","title":{"rendered":"Representantes do Peru visitam o Brasil para habilitar exporta\u00e7\u00f5es de s\u00eamen e embri\u00f5es bovinos"},"content":{"rendered":"\n<p><em>Veterin\u00e1rios do Servi\u00e7o Nacional de Sanidade Agr\u00e1ria (SENASA), do governo peruano, visitaram Central ABS, em Uberaba (MG), para assegurar qualidade dos produtos<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" height=\"682\" width=\"1024\" src=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/Visita-Peru.jpeg?w=1024\" alt=\"\" class=\"wp-image-7456\" srcset=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/Visita-Peru.jpeg 1600w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/Visita-Peru.jpeg?resize=300,200 300w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/Visita-Peru.jpeg?resize=768,512 768w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/Visita-Peru.jpeg?resize=1024,682 1024w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/Visita-Peru.jpeg?resize=1536,1023 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A gen\u00e9tica bovina brasileira \u00e9 refer\u00eancia mundial e conquista cada vez mais mercados. Os vizinhos peruanos tamb\u00e9m est\u00e3o de olho na gen\u00e9tica que acelera o progresso do rebanho nacional.<\/p>\n\n\n\n<p>Com o intuito de habilitar a ABS para exportar s\u00eamen e embri\u00f5es para o pa\u00eds, representantes do Servi\u00e7o Nacional de Sanidade Agr\u00e1ria (SENASA), do governo peruano, fizeram uma visita t\u00e9cnica na Central ABS em Uberaba, no Tri\u00e2ngulo Mineiro.<\/p>\n\n\n\n<p>\u201cO Peru tem grande demanda de gen\u00e9tica tropical. Nossos distribuidores ABS no Peru est\u00e3o pedindo. Ent\u00e3o estamos muito felizes em receber os representantes peruanos para demonstrar como tudo \u00e9 feito, e obter a habilita\u00e7\u00e3o para come\u00e7ar a exportar s\u00eamen e embri\u00f5es\u201d, salientou a Coordenadora de Com\u00e9rcio Exterior ABS, Paula Waeny.<\/p>\n\n\n\n<p>Ao longo do dia, os representantes do SENASA conheceram de perto a \u00e1rea de coleta de s\u00eamen, o n\u00facleo de doadoras de embri\u00f5es, quarentena, e os laborat\u00f3rios de embri\u00f5es, s\u00eamen convencional e s\u00eamen sexado.<\/p>\n\n\n\n<p>\u201cViemos para fazer essa inspe\u00e7\u00e3o \u2018in loco\u2019, com o objetivo de habilitar as exporta\u00e7\u00f5es. A gen\u00e9tica brasileira \u00e9 muito importante para os produtores do Peru porque \u00e9 uma gen\u00e9tica superior. Mas esse material gen\u00e9tico tem que ir para o nosso pa\u00eds acompanhado do bom cumprimento dos protocolos sanit\u00e1rios, ent\u00e3o \u00e9 isso que viemos assegurar\u201d, destacou o veterin\u00e1rio do SENASA, Daniel V\u00e1squez D\u00edaz.<\/p>\n\n\n\n<p>O Auditor Fiscal Agropecu\u00e1rio do Minist\u00e9rio da Agricultura e Pecu\u00e1ria do Brasil (Mapa), Fernando Augusto Santos, acompanhou a visita. \u201cOs pa\u00edses querem seguran\u00e7a sanit\u00e1ria e zoot\u00e9cnica do material gen\u00e9tico que est\u00e3o levando. Ent\u00e3o o papel do Mapa \u00e9 garantir a seguran\u00e7a de todos os processos de exporta\u00e7\u00e3o na central de gen\u00e9tica\u201d, enfatizou.<\/p>\n\n\n\n<p>A equipe do Departamento de Rela\u00e7\u00f5es Internacionais da Associa\u00e7\u00e3o Brasileira dos Criadores de Zebu (ABCZ), tamb\u00e9m atua na abertura dos mercados. \u201cPercebemos a grande demanda de protocolos sanit\u00e1rios e habilita\u00e7\u00f5es de empresas, como a ABS, por parte de outros pa\u00edses. Nesse contexto, por meio do Projeto Brazilian Cattle, Apex Brasil e ABCZ, temos conseguido encurtar caminhos e estabelecer novas parcerias\u201d, ressaltou Cynthia Ara\u00fajo Dutra, Analista de Rela\u00e7\u00f5es Internacionais da ABCZ.<\/p>\n\n\n\n<p>\u201cConstruindo essa rela\u00e7\u00e3o com outros pa\u00edses e trazendo os representantes para conhecer de perto a estrutura e os procedimentos operacionais das empresas, estamos possibilitando que a gen\u00e9tica brasileira cruze as fronteiras e beneficie o m\u00e1ximo de pecuaristas\u201d, completou Izabelle Jardim, tamb\u00e9m do Departamento Internacional da ABCZ.<\/p>\n\n\n\n<p>Marco Saravia Palomino, outro representante do Peru, ressaltou o rigor dos protocolos do pa\u00eds. \u201cH\u00e1 muita expectativa por parte dos produtores peruanos, mas temos que garantir que esse material gen\u00e9tico brasileiro est\u00e1 cumprindo todos os protocolos sanit\u00e1rios do nosso pa\u00eds\u201d.&nbsp;<\/p>\n\n\n\n<p>\u201cAl\u00e9m de analisar toda a parte de documenta\u00e7\u00e3o, eles conheceram de perto toda a estrutura e procedimentos adotados na ABS. Temos uma gen\u00e9tica de ponta, o melhor para fornecer a eles em quest\u00e3o de gen\u00e9tica, tanto de s\u00eamen como de embri\u00f5es\u201d, finalizou Ricardo Micai, m\u00e9dico veterin\u00e1rio da ABS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veterin\u00e1rios do Servi\u00e7o Nacional de Sanidade Agr\u00e1ria (SENASA), do governo peruano, visitaram Central ABS, em Uberaba (MG), para assegurar qualidade dos produtos A gen\u00e9tica bovina brasileira \u00e9 refer\u00eancia mundial e conquista cada vez mais mercados. Os vizinhos peruanos tamb\u00e9m est\u00e3o de olho na gen\u00e9tica que acelera o progresso do rebanho nacional. Com o intuito de [&hellip;]<\/p>\n","protected":false},"author":10336,"featured_media":0,"template":"","abs_news_category":[],"abs_news_tag":[],"class_list":["post-7455","abs_news_article","type-abs_news_article","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Representantes do Peru visitam o Brasil para habilitar exporta\u00e7\u00f5es de s\u00eamen e embri\u00f5es bovinos - ABS Global Brasil<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Representantes do Peru visitam o Brasil para habilitar exporta\u00e7\u00f5es de s\u00eamen e embri\u00f5es bovinos\" \/>\n<meta property=\"og:description\" content=\"Veterin\u00e1rios do Servi\u00e7o Nacional de Sanidade Agr\u00e1ria (SENASA), do governo peruano, visitaram Central ABS, em Uberaba (MG), para assegurar qualidade dos produtos A gen\u00e9tica bovina brasileira \u00e9 refer\u00eancia mundial e conquista cada vez mais mercados. Os vizinhos peruanos tamb\u00e9m est\u00e3o de olho na gen\u00e9tica que acelera o progresso do rebanho nacional. Com o intuito de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-09T12:06:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/Visita-Peru.jpeg?w=1024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/\",\"name\":\"Representantes do Peru visitam o Brasil para habilitar exporta\u00e7\u00f5es de s\u00eamen e embri\u00f5es bovinos - ABS Global Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/Visita-Peru.jpeg?w=1024\",\"datePublished\":\"2023-11-09T12:06:30+00:00\",\"dateModified\":\"2023-11-09T12:06:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/#primaryimage\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/Visita-Peru.jpeg\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/Visita-Peru.jpeg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Representantes do Peru visitam o Brasil para habilitar exporta\u00e7\u00f5es de s\u00eamen e embri\u00f5es bovinos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"name\":\"ABS Global Brasil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\",\"name\":\"ABS Global Brasil\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Brasil \"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Representantes do Peru visitam o Brasil para habilitar exporta\u00e7\u00f5es de s\u00eamen e embri\u00f5es bovinos - ABS Global Brasil","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Representantes do Peru visitam o Brasil para habilitar exporta\u00e7\u00f5es de s\u00eamen e embri\u00f5es bovinos","og_description":"Veterin\u00e1rios do Servi\u00e7o Nacional de Sanidade Agr\u00e1ria (SENASA), do governo peruano, visitaram Central ABS, em Uberaba (MG), para assegurar qualidade dos produtos A gen\u00e9tica bovina brasileira \u00e9 refer\u00eancia mundial e conquista cada vez mais mercados. Os vizinhos peruanos tamb\u00e9m est\u00e3o de olho na gen\u00e9tica que acelera o progresso do rebanho nacional. Com o intuito de [&hellip;]","og_url":"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/","og_site_name":"ABS Global Brasil","article_modified_time":"2023-11-09T12:06:31+00:00","og_image":[{"url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/Visita-Peru.jpeg?w=1024","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/","url":"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/","name":"Representantes do Peru visitam o Brasil para habilitar exporta\u00e7\u00f5es de s\u00eamen e embri\u00f5es bovinos - ABS Global Brasil","isPartOf":{"@id":"https:\/\/www-test.absglobal.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/#primaryimage"},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/#primaryimage"},"thumbnailUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/Visita-Peru.jpeg?w=1024","datePublished":"2023-11-09T12:06:30+00:00","dateModified":"2023-11-09T12:06:31+00:00","breadcrumb":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/#primaryimage","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/Visita-Peru.jpeg","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/Visita-Peru.jpeg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/representantes-do-peru-visitam-o-brasil-para-habilitar-exportacoes-de-semen-e-embrioes-bovinos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-test.absglobal.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www-test.absglobal.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Representantes do Peru visitam o Brasil para habilitar exporta\u00e7\u00f5es de s\u00eamen e embri\u00f5es bovinos"}]},{"@type":"WebSite","@id":"https:\/\/www-test.absglobal.com\/br\/#website","url":"https:\/\/www-test.absglobal.com\/br\/","name":"ABS Global Brasil","description":"","publisher":{"@id":"https:\/\/www-test.absglobal.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www-test.absglobal.com\/br\/#organization","name":"ABS Global Brasil","url":"https:\/\/www-test.absglobal.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Brasil "},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article\/7455"}],"collection":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/users\/10336"}],"wp:attachment":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media?parent=7455"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_category?post=7455"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_tag?post=7455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}