{"id":7453,"date":"2023-11-08T05:54:54","date_gmt":"2023-11-08T10:54:54","guid":{"rendered":"https:\/\/www-test.absglobal.com\/br\/?post_type=abs_news_article&#038;p=7453"},"modified":"2023-11-08T05:54:55","modified_gmt":"2023-11-08T10:54:55","slug":"morre-vaca-ich-canela-teatro-icone-da-raca-girolando","status":"publish","type":"abs_news_article","link":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/","title":{"rendered":"Morre vaca ICH Canela Teatro, \u00edcone da ra\u00e7a Girolando"},"content":{"rendered":"\n<p><em>Com 163 filhas e 64 filhos registrados, ICH Canela Teatro deixa legado para pecu\u00e1ria leiteira nacional<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"473\" src=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/ich-canela-teatro-s-3377-768x473-1.jpg\" alt=\"\" class=\"wp-image-7454\" srcset=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/ich-canela-teatro-s-3377-768x473-1.jpg 768w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/ich-canela-teatro-s-3377-768x473-1.jpg?resize=300,185 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>A pecu\u00e1ria leiteira nacional perdeu nesta ter\u00e7a-feira (7), uma de suas mais importantes vacas da ra\u00e7a Girolando. ICH Canela Teatro ficou conhecida principalmente pela qualidade de suas prog\u00eanies.&nbsp;<\/p>\n\n\n\n<p>\u201cNossa eterna ICH Canela Teatro. Suas filhas e netas, al\u00e9m de muito produtivas, s\u00e3o campe\u00e3s de pista e torneio leiteiro nas maiores exposi\u00e7\u00f5es do Brasil\u201d, publicou o pecuarista, Jos\u00e9 Renato Chiari, no perfil da ICH Agropastoril no Instagram.<\/p>\n\n\n\n<p>Com 163 filhas e 64 filhos registrados, e mais de 15 filhos e 25 netos em centrais de gen\u00e9tica, ICH Canela Teatro deixa expressivo volume gen\u00e9tico na Central ABS. \u201cCanela merece toda homenagem pela qualidade de suas prog\u00eanies. Quebrou o paradigma de que s\u00f3 reprodutores fossem refer\u00eancia de melhoramento gen\u00e9tico. Uma vaca que fica registrada na hist\u00f3ria da ra\u00e7a Girolando como uma das mais importantes f\u00eameas, por sua grande contribui\u00e7\u00e3o \u00e0 produ\u00e7\u00e3o leiteira\u201d, destacou o Coordenador de Produto e Atendimento ao Cliente Leite da ABS, Fernando Rosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com 163 filhas e 64 filhos registrados, ICH Canela Teatro deixa legado para pecu\u00e1ria leiteira nacional A pecu\u00e1ria leiteira nacional perdeu nesta ter\u00e7a-feira (7), uma de suas mais importantes vacas da ra\u00e7a Girolando. ICH Canela Teatro ficou conhecida principalmente pela qualidade de suas prog\u00eanies.&nbsp; \u201cNossa eterna ICH Canela Teatro. Suas filhas e netas, al\u00e9m de [&hellip;]<\/p>\n","protected":false},"author":10336,"featured_media":0,"template":"","abs_news_category":[],"abs_news_tag":[],"class_list":["post-7453","abs_news_article","type-abs_news_article","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Morre vaca ICH Canela Teatro, \u00edcone da ra\u00e7a Girolando - ABS Global Brasil<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Morre vaca ICH Canela Teatro, \u00edcone da ra\u00e7a Girolando\" \/>\n<meta property=\"og:description\" content=\"Com 163 filhas e 64 filhos registrados, ICH Canela Teatro deixa legado para pecu\u00e1ria leiteira nacional A pecu\u00e1ria leiteira nacional perdeu nesta ter\u00e7a-feira (7), uma de suas mais importantes vacas da ra\u00e7a Girolando. ICH Canela Teatro ficou conhecida principalmente pela qualidade de suas prog\u00eanies.&nbsp; \u201cNossa eterna ICH Canela Teatro. Suas filhas e netas, al\u00e9m de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-08T10:54:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/ich-canela-teatro-s-3377-768x473-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/\",\"name\":\"Morre vaca ICH Canela Teatro, \u00edcone da ra\u00e7a Girolando - ABS Global Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/ich-canela-teatro-s-3377-768x473-1.jpg\",\"datePublished\":\"2023-11-08T10:54:54+00:00\",\"dateModified\":\"2023-11-08T10:54:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/#primaryimage\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/ich-canela-teatro-s-3377-768x473-1.jpg\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/ich-canela-teatro-s-3377-768x473-1.jpg\",\"width\":768,\"height\":473},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Morre vaca ICH Canela Teatro, \u00edcone da ra\u00e7a Girolando\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"name\":\"ABS Global Brasil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\",\"name\":\"ABS Global Brasil\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Brasil \"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Morre vaca ICH Canela Teatro, \u00edcone da ra\u00e7a Girolando - ABS Global Brasil","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Morre vaca ICH Canela Teatro, \u00edcone da ra\u00e7a Girolando","og_description":"Com 163 filhas e 64 filhos registrados, ICH Canela Teatro deixa legado para pecu\u00e1ria leiteira nacional A pecu\u00e1ria leiteira nacional perdeu nesta ter\u00e7a-feira (7), uma de suas mais importantes vacas da ra\u00e7a Girolando. ICH Canela Teatro ficou conhecida principalmente pela qualidade de suas prog\u00eanies.&nbsp; \u201cNossa eterna ICH Canela Teatro. Suas filhas e netas, al\u00e9m de [&hellip;]","og_url":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/","og_site_name":"ABS Global Brasil","article_modified_time":"2023-11-08T10:54:55+00:00","og_image":[{"url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/ich-canela-teatro-s-3377-768x473-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/","url":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/","name":"Morre vaca ICH Canela Teatro, \u00edcone da ra\u00e7a Girolando - ABS Global Brasil","isPartOf":{"@id":"https:\/\/www-test.absglobal.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/#primaryimage"},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/#primaryimage"},"thumbnailUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/ich-canela-teatro-s-3377-768x473-1.jpg","datePublished":"2023-11-08T10:54:54+00:00","dateModified":"2023-11-08T10:54:55+00:00","breadcrumb":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/#primaryimage","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/ich-canela-teatro-s-3377-768x473-1.jpg","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/11\/ich-canela-teatro-s-3377-768x473-1.jpg","width":768,"height":473},{"@type":"BreadcrumbList","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/morre-vaca-ich-canela-teatro-icone-da-raca-girolando\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-test.absglobal.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www-test.absglobal.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Morre vaca ICH Canela Teatro, \u00edcone da ra\u00e7a Girolando"}]},{"@type":"WebSite","@id":"https:\/\/www-test.absglobal.com\/br\/#website","url":"https:\/\/www-test.absglobal.com\/br\/","name":"ABS Global Brasil","description":"","publisher":{"@id":"https:\/\/www-test.absglobal.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www-test.absglobal.com\/br\/#organization","name":"ABS Global Brasil","url":"https:\/\/www-test.absglobal.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Brasil "},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article\/7453"}],"collection":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/users\/10336"}],"wp:attachment":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media?parent=7453"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_category?post=7453"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_tag?post=7453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}