{"id":6423,"date":"2023-06-16T15:44:27","date_gmt":"2023-06-16T20:44:27","guid":{"rendered":"https:\/\/www-test.absglobal.com\/br\/?post_type=abs_news_article&#038;p=6423"},"modified":"2023-06-16T15:44:28","modified_gmt":"2023-06-16T20:44:28","slug":"abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina","status":"publish","type":"abs_news_article","link":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/","title":{"rendered":"ABS participa de maior evento de Andrologia Animal da Am\u00e9rica Latina"},"content":{"rendered":"\n<p><em>VII Reuni\u00e3o Anual da ABRAA acontece em Salvador (BA), at\u00e9 este s\u00e1bado (17)<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" height=\"1024\" width=\"532\" src=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/06\/A-partir-da-esquerda-Ana-Clara-de-Avila-Amanda-Nonato-e-Adolfo-Ferreira.jpeg?w=532\" alt=\"\" class=\"wp-image-6424\" srcset=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/06\/A-partir-da-esquerda-Ana-Clara-de-Avila-Amanda-Nonato-e-Adolfo-Ferreira.jpeg 721w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/06\/A-partir-da-esquerda-Ana-Clara-de-Avila-Amanda-Nonato-e-Adolfo-Ferreira.jpeg?resize=156,300 156w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/06\/A-partir-da-esquerda-Ana-Clara-de-Avila-Amanda-Nonato-e-Adolfo-Ferreira.jpeg?resize=532,1024 532w\" sizes=\"(max-width: 532px) 100vw, 532px\" \/><\/figure>\n\n\n\n<p>A ABS, l\u00edder mundial em gen\u00e9tica bovina, participa do maior evento de Andrologia Animal da Am\u00e9rica Latina: VII Reuni\u00e3o Anual da Associa\u00e7\u00e3o Brasileira de Andrologia Animal (ABRAA), que este ano acontece em Salvador (BA).<\/p>\n\n\n\n<p>Com o prop\u00f3sito de gerar atualiza\u00e7\u00e3o cient\u00edfica e aprofundamento t\u00e9cnico acerca das novas tecnologias no mercado de gen\u00e9tica, o evento re\u00fane profissionais de Ci\u00eancias Agr\u00e1rias de todo o pa\u00eds e especialistas renomados no segmento. A programa\u00e7\u00e3o inclui mesas-redondas, palestras e workshops.<\/p>\n\n\n\n<p>O Gerente de Produ\u00e7\u00e3o da ABS, Adolfo Ferreira, participou como moderador de uma mesa-redonda que debateu quest\u00f5es qualitativas e legislativas da andrologia. \u201cDiscutimos n\u00e3o s\u00f3 par\u00e2metros legais que envolvem a produ\u00e7\u00e3o, industrializa\u00e7\u00e3o e comercializa\u00e7\u00e3o de s\u00eamen no Brasil, mas tamb\u00e9m aspectos de futuro, como novas pesquisas e tecnologias. Um evento de alto n\u00edvel t\u00e9cnico, que tem total rela\u00e7\u00e3o com o que o fazemos: produ\u00e7\u00e3o e multiplica\u00e7\u00e3o de gen\u00e9tica bovina por meio de s\u00eamen convencional, sexado e embri\u00f5es\u201d, destacou Adolfo Ferreira.<\/p>\n\n\n\n<p>Tamb\u00e9m participam do encontro a Coordenadora do Laborat\u00f3rio de Produ\u00e7\u00e3o de S\u00eamen Convencional, Ana Clara de \u00c1vila, e a Gerente do Laborat\u00f3rio IntelliGen, respons\u00e1vel pela produ\u00e7\u00e3o de gen\u00e9tica sexada Sexcel, Amanda Nonato.<\/p>\n\n\n\n<p>\u201cO evento da ABRAA re\u00fane todo o setor de reprodu\u00e7\u00e3o animal: comunidade acad\u00eamica, centrais de gen\u00e9tica e empresas relacionadas, al\u00e9m de profissionais aut\u00f4nomos. \u00c9 uma oportunidade de nos atualizar, trocar experi\u00eancias e discutir como podemos auxiliar uns aos outros, afinal nosso objetivo \u00e9 o mesmo, proporcionar avan\u00e7o gen\u00e9tico aos produtores\u201d, finaliza Amanda Nonato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VII Reuni\u00e3o Anual da ABRAA acontece em Salvador (BA), at\u00e9 este s\u00e1bado (17) A ABS, l\u00edder mundial em gen\u00e9tica bovina, participa do maior evento de Andrologia Animal da Am\u00e9rica Latina: VII Reuni\u00e3o Anual da Associa\u00e7\u00e3o Brasileira de Andrologia Animal (ABRAA), que este ano acontece em Salvador (BA). Com o prop\u00f3sito de gerar atualiza\u00e7\u00e3o cient\u00edfica e [&hellip;]<\/p>\n","protected":false},"author":10336,"featured_media":0,"template":"","abs_news_category":[],"abs_news_tag":[],"class_list":["post-6423","abs_news_article","type-abs_news_article","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ABS participa de maior evento de Andrologia Animal da Am\u00e9rica Latina - ABS Global Brasil<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABS participa de maior evento de Andrologia Animal da Am\u00e9rica Latina\" \/>\n<meta property=\"og:description\" content=\"VII Reuni\u00e3o Anual da ABRAA acontece em Salvador (BA), at\u00e9 este s\u00e1bado (17) A ABS, l\u00edder mundial em gen\u00e9tica bovina, participa do maior evento de Andrologia Animal da Am\u00e9rica Latina: VII Reuni\u00e3o Anual da Associa\u00e7\u00e3o Brasileira de Andrologia Animal (ABRAA), que este ano acontece em Salvador (BA). Com o prop\u00f3sito de gerar atualiza\u00e7\u00e3o cient\u00edfica e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-16T20:44:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/06\/A-partir-da-esquerda-Ana-Clara-de-Avila-Amanda-Nonato-e-Adolfo-Ferreira.jpeg?w=532\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/\",\"name\":\"ABS participa de maior evento de Andrologia Animal da Am\u00e9rica Latina - ABS Global Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/06\/A-partir-da-esquerda-Ana-Clara-de-Avila-Amanda-Nonato-e-Adolfo-Ferreira.jpeg?w=532\",\"datePublished\":\"2023-06-16T20:44:27+00:00\",\"dateModified\":\"2023-06-16T20:44:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/#primaryimage\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/06\/A-partir-da-esquerda-Ana-Clara-de-Avila-Amanda-Nonato-e-Adolfo-Ferreira.jpeg\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/06\/A-partir-da-esquerda-Ana-Clara-de-Avila-Amanda-Nonato-e-Adolfo-Ferreira.jpeg\",\"width\":721,\"height\":1387},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ABS participa de maior evento de Andrologia Animal da Am\u00e9rica Latina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"name\":\"ABS Global Brasil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\",\"name\":\"ABS Global Brasil\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Brasil \"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ABS participa de maior evento de Andrologia Animal da Am\u00e9rica Latina - ABS Global Brasil","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"ABS participa de maior evento de Andrologia Animal da Am\u00e9rica Latina","og_description":"VII Reuni\u00e3o Anual da ABRAA acontece em Salvador (BA), at\u00e9 este s\u00e1bado (17) A ABS, l\u00edder mundial em gen\u00e9tica bovina, participa do maior evento de Andrologia Animal da Am\u00e9rica Latina: VII Reuni\u00e3o Anual da Associa\u00e7\u00e3o Brasileira de Andrologia Animal (ABRAA), que este ano acontece em Salvador (BA). Com o prop\u00f3sito de gerar atualiza\u00e7\u00e3o cient\u00edfica e [&hellip;]","og_url":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/","og_site_name":"ABS Global Brasil","article_modified_time":"2023-06-16T20:44:28+00:00","og_image":[{"url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/06\/A-partir-da-esquerda-Ana-Clara-de-Avila-Amanda-Nonato-e-Adolfo-Ferreira.jpeg?w=532","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/","url":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/","name":"ABS participa de maior evento de Andrologia Animal da Am\u00e9rica Latina - ABS Global Brasil","isPartOf":{"@id":"https:\/\/www-test.absglobal.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/#primaryimage"},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/#primaryimage"},"thumbnailUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/06\/A-partir-da-esquerda-Ana-Clara-de-Avila-Amanda-Nonato-e-Adolfo-Ferreira.jpeg?w=532","datePublished":"2023-06-16T20:44:27+00:00","dateModified":"2023-06-16T20:44:28+00:00","breadcrumb":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/#primaryimage","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/06\/A-partir-da-esquerda-Ana-Clara-de-Avila-Amanda-Nonato-e-Adolfo-Ferreira.jpeg","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2023\/06\/A-partir-da-esquerda-Ana-Clara-de-Avila-Amanda-Nonato-e-Adolfo-Ferreira.jpeg","width":721,"height":1387},{"@type":"BreadcrumbList","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-participa-de-maior-evento-de-andrologia-animal-da-america-latina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-test.absglobal.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www-test.absglobal.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"ABS participa de maior evento de Andrologia Animal da Am\u00e9rica Latina"}]},{"@type":"WebSite","@id":"https:\/\/www-test.absglobal.com\/br\/#website","url":"https:\/\/www-test.absglobal.com\/br\/","name":"ABS Global Brasil","description":"","publisher":{"@id":"https:\/\/www-test.absglobal.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www-test.absglobal.com\/br\/#organization","name":"ABS Global Brasil","url":"https:\/\/www-test.absglobal.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Brasil "},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article\/6423"}],"collection":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/users\/10336"}],"wp:attachment":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media?parent=6423"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_category?post=6423"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_tag?post=6423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}