{"id":5765,"date":"2022-04-28T09:09:27","date_gmt":"2022-04-28T14:09:27","guid":{"rendered":"https:\/\/www-test.absglobal.com\/br\/?post_type=abs_news_article&#038;p=5765"},"modified":"2022-04-29T11:05:31","modified_gmt":"2022-04-29T16:05:31","slug":"desfile-de-touros-volta-a-ser-destaque-da-programacao-da-expozebu","status":"publish","type":"abs_news_article","link":"https:\/\/www-test.absglobal.com\/br\/noticias\/desfile-de-touros-volta-a-ser-destaque-da-programacao-da-expozebu\/","title":{"rendered":"Desfile de Touros volta a ser destaque da programa\u00e7\u00e3o da ExpoZebu"},"content":{"rendered":"\n<p><em>Tradicional evento realizado em Uberaba (MG) retorna ao seu formato presencial; a\u00e7\u00e3o acontece no dia 2 de maio<\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-embed-handler wp-block-embed-embed-handler wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Desfile de Touros ABS - Voc\u00ea \u00e9 nosso convidado! #ABSNAEXPOZEBU\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/ByiFIXNr5eM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>O regresso das a\u00e7\u00f5es presenciais da ExpoZebu est\u00e1 movimentando a cidade de Uberaba (MG), conhecida como a capital do Zebu. Com a expectativa de uma edi\u00e7\u00e3o marcada pelo regresso \u00e0s atividades tradicionais, a maior feira da pecu\u00e1ria zebu\u00edna do mundo levar\u00e1 mais experi\u00eancias que nunca para pecuaristas e o p\u00fablico geral.&nbsp;<\/p>\n\n\n\n<p>Entre os eventos que far\u00e3o seu regresso na edi\u00e7\u00e3o de 2022, est\u00e1 em destaque o Desfile de Touros da ABS, que volta a ser realizado de forma presencial na Central ABS \u2013 ser\u00e1 no dia 2 de maio, entre as 14h e 18h. Pensada como uma oportunidade para promover o reencontro da empresa com o cliente, a edi\u00e7\u00e3o deste ano apresentar\u00e1 as \u00faltimas novidades das baterias de Corte e Leite da ABS.&nbsp;<\/p>\n\n\n\n<p>&#8220;Em nossa central de biotecnologia, iremos realizar um Desfile de Touros para apresentar a todos o nosso orgulho da maior bateria de touros de corte e leite do mercado! Al\u00e9m disso, nossa casa estar\u00e1 aberta a visitas guiadas pelo nosso time t\u00e9cnico, e o produtor est\u00e1 convidado a conversar conosco sobre melhoramento gen\u00e9tico e sobre como aumentar a velocidade desse progresso com solu\u00e7\u00f5es ABS como os embri\u00f5es ABS NEO e a gen\u00e9tica sexada Sexcel&#8221;, descreve o diretor geral da ABS Brasil, Marcio Nery.&nbsp;<\/p>\n\n\n\n<p>Como em edi\u00e7\u00f5es anteriores, o Desfile de Touros ser\u00e1 dividido de acordo com as baterias de Corte e Leite. Desta forma, seja qual for o sistema produtivo ou perfil do rebanho, o pecuarista pode ter a certeza que encontrar\u00e1 boas novidades durante o evento.&nbsp;<\/p>\n\n\n\n<p><strong>Leite.<\/strong>&nbsp;O Desfile de Touros deste ano traz como novidade a apresenta\u00e7\u00e3o conduzida por presidentes das associa\u00e7\u00f5es de ra\u00e7as leiteiras, promovendo discuss\u00f5es relevantes sobre o cen\u00e1rio atual de cada ra\u00e7a e o seu futuro em rela\u00e7\u00e3o \u00e0 gen\u00e9tica, como afirma o Gerente de Produto e Atendimento ao Cliente Leite da ABS, Fernando Rosa.&nbsp;<br>&#8220;Contar com a presen\u00e7a dos presidentes das associa\u00e7\u00f5es \u00e9 muito importante, j\u00e1 que isso proporciona diversas discuss\u00f5es importantes e pode, at\u00e9, ajudar a definir o direcionamento das novas sele\u00e7\u00f5es gen\u00e9ticas&#8221;, ressalta.&nbsp;<\/p>\n\n\n\n<p><strong>Corte.<\/strong>&nbsp;J\u00e1 para as ra\u00e7as de corte, o Gerente de Mercado e Contas-Chave Corte da ABS, Gustavo Morales, destaca a import\u00e2ncia do regresso \u00e0s atividades presenciais ap\u00f3s dois anos.&nbsp;<br>&#8220;Al\u00e9m de uma valiosa oportunidade para conhecer de perto a melhor bateria de touros zebu\u00ednos do mercado, o Desfile de Touros deste ano \u00e9 uma excelente chance para o produtor conferir o que a equipe ABS realizou de renova\u00e7\u00e3o nos \u00faltimos dois anos&#8221;, enfatiza.&nbsp;<\/p>\n\n\n\n<p><strong>Transmiss\u00e3o.<\/strong>&nbsp;Al\u00e9m da realiza\u00e7\u00e3o do evento presencial, o Desfile de Touros tamb\u00e9m ser\u00e1 transmitido ao vivo pelo canal de YouTube da ABS, para aqueles que n\u00e3o puderem acompanhar a a\u00e7\u00e3o pessoalmente:<a href=\"https:\/\/youtu.be\/gpx8kHG_aXc\" target=\"_blank\" rel=\"noreferrer noopener\"> https:\/\/youtu.be\/gpx8kH<\/a><a href=\"https:\/\/www.youtube.com\/user\/ABSPecplan\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">G_aXc<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tradicional evento realizado em Uberaba (MG) retorna ao seu formato presencial; a\u00e7\u00e3o acontece no dia 2 de maio O regresso das a\u00e7\u00f5es presenciais da ExpoZebu est\u00e1 movimentando a cidade de Uberaba (MG), conhecida como a capital do Zebu. Com a expectativa de uma edi\u00e7\u00e3o marcada pelo regresso \u00e0s atividades tradicionais, a maior feira da pecu\u00e1ria [&hellip;]<\/p>\n","protected":false},"author":342,"featured_media":0,"template":"","abs_news_category":[73],"abs_news_tag":[77,76],"class_list":["post-5765","abs_news_article","type-abs_news_article","status-publish","hentry","abs_news_category-noticias","abs_news_tag-corte","abs_news_tag-leite","ep_custom_result-corte","ep_custom_result-leite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Desfile de Touros volta a ser destaque da programa\u00e7\u00e3o da ExpoZebu - ABS Global Brasil<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desfile de Touros volta a ser destaque da programa\u00e7\u00e3o da ExpoZebu\" \/>\n<meta property=\"og:description\" content=\"Tradicional evento realizado em Uberaba (MG) retorna ao seu formato presencial; a\u00e7\u00e3o acontece no dia 2 de maio O regresso das a\u00e7\u00f5es presenciais da ExpoZebu est\u00e1 movimentando a cidade de Uberaba (MG), conhecida como a capital do Zebu. Com a expectativa de uma edi\u00e7\u00e3o marcada pelo regresso \u00e0s atividades tradicionais, a maior feira da pecu\u00e1ria [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-test.absglobal.com\/br\/noticias\/desfile-de-touros-volta-a-ser-destaque-da-programacao-da-expozebu\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-29T16:05:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/desfile-de-touros-volta-a-ser-destaque-da-programacao-da-expozebu\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/desfile-de-touros-volta-a-ser-destaque-da-programacao-da-expozebu\/\",\"name\":\"Desfile de Touros volta a ser destaque da programa\u00e7\u00e3o da ExpoZebu - ABS Global Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\"},\"datePublished\":\"2022-04-28T14:09:27+00:00\",\"dateModified\":\"2022-04-29T16:05:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/desfile-de-touros-volta-a-ser-destaque-da-programacao-da-expozebu\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-test.absglobal.com\/br\/noticias\/desfile-de-touros-volta-a-ser-destaque-da-programacao-da-expozebu\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/desfile-de-touros-volta-a-ser-destaque-da-programacao-da-expozebu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Desfile de Touros volta a ser destaque da programa\u00e7\u00e3o da ExpoZebu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"name\":\"ABS Global Brasil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\",\"name\":\"ABS Global Brasil\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Brasil \"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Desfile de Touros volta a ser destaque da programa\u00e7\u00e3o da ExpoZebu - ABS Global Brasil","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Desfile de Touros volta a ser destaque da programa\u00e7\u00e3o da ExpoZebu","og_description":"Tradicional evento realizado em Uberaba (MG) retorna ao seu formato presencial; a\u00e7\u00e3o acontece no dia 2 de maio O regresso das a\u00e7\u00f5es presenciais da ExpoZebu est\u00e1 movimentando a cidade de Uberaba (MG), conhecida como a capital do Zebu. Com a expectativa de uma edi\u00e7\u00e3o marcada pelo regresso \u00e0s atividades tradicionais, a maior feira da pecu\u00e1ria [&hellip;]","og_url":"https:\/\/www-test.absglobal.com\/br\/noticias\/desfile-de-touros-volta-a-ser-destaque-da-programacao-da-expozebu\/","og_site_name":"ABS Global Brasil","article_modified_time":"2022-04-29T16:05:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/desfile-de-touros-volta-a-ser-destaque-da-programacao-da-expozebu\/","url":"https:\/\/www-test.absglobal.com\/br\/noticias\/desfile-de-touros-volta-a-ser-destaque-da-programacao-da-expozebu\/","name":"Desfile de Touros volta a ser destaque da programa\u00e7\u00e3o da ExpoZebu - ABS Global Brasil","isPartOf":{"@id":"https:\/\/www-test.absglobal.com\/br\/#website"},"datePublished":"2022-04-28T14:09:27+00:00","dateModified":"2022-04-29T16:05:31+00:00","breadcrumb":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/desfile-de-touros-volta-a-ser-destaque-da-programacao-da-expozebu\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-test.absglobal.com\/br\/noticias\/desfile-de-touros-volta-a-ser-destaque-da-programacao-da-expozebu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/desfile-de-touros-volta-a-ser-destaque-da-programacao-da-expozebu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-test.absglobal.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www-test.absglobal.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Desfile de Touros volta a ser destaque da programa\u00e7\u00e3o da ExpoZebu"}]},{"@type":"WebSite","@id":"https:\/\/www-test.absglobal.com\/br\/#website","url":"https:\/\/www-test.absglobal.com\/br\/","name":"ABS Global Brasil","description":"","publisher":{"@id":"https:\/\/www-test.absglobal.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www-test.absglobal.com\/br\/#organization","name":"ABS Global Brasil","url":"https:\/\/www-test.absglobal.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Brasil "},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article\/5765"}],"collection":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/users\/342"}],"wp:attachment":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media?parent=5765"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_category?post=5765"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_tag?post=5765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}