{"id":5507,"date":"2021-12-20T07:23:05","date_gmt":"2021-12-20T12:23:05","guid":{"rendered":"https:\/\/www-test.absglobal.com\/br\/?post_type=abs_news_article&#038;p=5507"},"modified":"2021-12-20T07:23:06","modified_gmt":"2021-12-20T12:23:06","slug":"abs-abre-novo-escritorio-em-patos-de-minas-mg","status":"publish","type":"abs_news_article","link":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/","title":{"rendered":"ABS abre novo escrit\u00f3rio em Patos de Minas (MG)"},"content":{"rendered":"\n<p><em>Amplia\u00e7\u00e3o da rede comercial da empresa consolida oferta de solu\u00e7\u00f5es gen\u00e9ticas em uma das principais bacias leiteiras do pa\u00eds<\/em><\/p>\n\n\n\n<p>A ABS, empresa l\u00edder do setor de gen\u00e9tica bovina, inaugurou um novo escrit\u00f3rio na cidade de Patos de Minas (MG), aproximando os produtores locais aos produtos e servi\u00e7os ABS e consolidando a sua presen\u00e7a permanente em uma das principais regi\u00f5es produtoras de leite do Brasil.<\/p>\n\n\n\n<p>A nova unidade \u00e9 resultado da amplia\u00e7\u00e3o dos neg\u00f3cios da FortS\u00eamen, representante local da ABS. Para o supervisor da ABS na regi\u00e3o Sudeste, Odilon Rezende, a abertura do escrit\u00f3rio significa, mais que uma a\u00e7\u00e3o estrat\u00e9gica da empresa, uma forma de aprimorar o atendimento aos produtores de carne e leite da regi\u00e3o.<\/p>\n\n\n\n<p>&#8220;Para n\u00f3s, \u00e9 de extrema import\u00e2ncia contarmos com uma extens\u00e3o da ABS em uma das principais bacias leiteiras do pa\u00eds, tanto em volume, quanto em tecnologia. Com a nova sede, mais produtores ter\u00e3o acesso ao portf\u00f3lio de produtos e servi\u00e7os da ABS&#8221;, comenta.<\/p>\n\n\n\n<p>Da mesma forma, o gerente comercial da empresa, Alexandre Lima, comemora mais um passo dado pela empresa l\u00edder do setor.<\/p>\n\n\n\n<p>&#8220;Mais uma vez, a ABS preserva a integridade de um dos seus maiores valores \u2013 atrav\u00e9s da sua competente rede de vendas, prover solu\u00e7\u00f5es gen\u00e9ticas, mantendo o cliente na centralidade do trabalho t\u00e9cnico consultivo a campo. Agora, \u00e9 a vez da FortS\u00eamen de ampliar os seus neg\u00f3cios em Patos de Minas, pronta para atender aos produtores nesta regi\u00e3o t\u00e3o importante para a pecu\u00e1ria leiteira&#8221;, finaliza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amplia\u00e7\u00e3o da rede comercial da empresa consolida oferta de solu\u00e7\u00f5es gen\u00e9ticas em uma das principais bacias leiteiras do pa\u00eds A ABS, empresa l\u00edder do setor de gen\u00e9tica bovina, inaugurou um novo escrit\u00f3rio na cidade de Patos de Minas (MG), aproximando os produtores locais aos produtos e servi\u00e7os ABS e consolidando a sua presen\u00e7a permanente em [&hellip;]<\/p>\n","protected":false},"author":342,"featured_media":5508,"template":"","abs_news_category":[73],"abs_news_tag":[77,76],"class_list":["post-5507","abs_news_article","type-abs_news_article","status-publish","has-post-thumbnail","hentry","abs_news_category-noticias","abs_news_tag-corte","abs_news_tag-leite","ep_custom_result-corte","ep_custom_result-leite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ABS abre novo escrit\u00f3rio em Patos de Minas (MG) - ABS Global Brasil<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABS abre novo escrit\u00f3rio em Patos de Minas (MG)\" \/>\n<meta property=\"og:description\" content=\"Amplia\u00e7\u00e3o da rede comercial da empresa consolida oferta de solu\u00e7\u00f5es gen\u00e9ticas em uma das principais bacias leiteiras do pa\u00eds A ABS, empresa l\u00edder do setor de gen\u00e9tica bovina, inaugurou um novo escrit\u00f3rio na cidade de Patos de Minas (MG), aproximando os produtores locais aos produtos e servi\u00e7os ABS e consolidando a sua presen\u00e7a permanente em [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-20T12:23:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/12\/WhatsApp-Image-2021-12-17-at-16.03.59.jpeg?fit=1280%2C960\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/\",\"name\":\"ABS abre novo escrit\u00f3rio em Patos de Minas (MG) - ABS Global Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/12\/WhatsApp-Image-2021-12-17-at-16.03.59.jpeg\",\"datePublished\":\"2021-12-20T12:23:05+00:00\",\"dateModified\":\"2021-12-20T12:23:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/#primaryimage\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/12\/WhatsApp-Image-2021-12-17-at-16.03.59.jpeg\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/12\/WhatsApp-Image-2021-12-17-at-16.03.59.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ABS abre novo escrit\u00f3rio em Patos de Minas (MG)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"name\":\"ABS Global Brasil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\",\"name\":\"ABS Global Brasil\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Brasil \"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ABS abre novo escrit\u00f3rio em Patos de Minas (MG) - ABS Global Brasil","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"ABS abre novo escrit\u00f3rio em Patos de Minas (MG)","og_description":"Amplia\u00e7\u00e3o da rede comercial da empresa consolida oferta de solu\u00e7\u00f5es gen\u00e9ticas em uma das principais bacias leiteiras do pa\u00eds A ABS, empresa l\u00edder do setor de gen\u00e9tica bovina, inaugurou um novo escrit\u00f3rio na cidade de Patos de Minas (MG), aproximando os produtores locais aos produtos e servi\u00e7os ABS e consolidando a sua presen\u00e7a permanente em [&hellip;]","og_url":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/","og_site_name":"ABS Global Brasil","article_modified_time":"2021-12-20T12:23:06+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/12\/WhatsApp-Image-2021-12-17-at-16.03.59.jpeg?fit=1280%2C960","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/","url":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/","name":"ABS abre novo escrit\u00f3rio em Patos de Minas (MG) - ABS Global Brasil","isPartOf":{"@id":"https:\/\/www-test.absglobal.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/#primaryimage"},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/#primaryimage"},"thumbnailUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/12\/WhatsApp-Image-2021-12-17-at-16.03.59.jpeg","datePublished":"2021-12-20T12:23:05+00:00","dateModified":"2021-12-20T12:23:06+00:00","breadcrumb":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/#primaryimage","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/12\/WhatsApp-Image-2021-12-17-at-16.03.59.jpeg","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/12\/WhatsApp-Image-2021-12-17-at-16.03.59.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-abre-novo-escritorio-em-patos-de-minas-mg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-test.absglobal.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www-test.absglobal.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"ABS abre novo escrit\u00f3rio em Patos de Minas (MG)"}]},{"@type":"WebSite","@id":"https:\/\/www-test.absglobal.com\/br\/#website","url":"https:\/\/www-test.absglobal.com\/br\/","name":"ABS Global Brasil","description":"","publisher":{"@id":"https:\/\/www-test.absglobal.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www-test.absglobal.com\/br\/#organization","name":"ABS Global Brasil","url":"https:\/\/www-test.absglobal.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Brasil "},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article\/5507"}],"collection":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/users\/342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media\/5508"}],"wp:attachment":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media?parent=5507"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_category?post=5507"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_tag?post=5507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}