{"id":5445,"date":"2021-11-11T09:19:49","date_gmt":"2021-11-11T14:19:49","guid":{"rendered":"https:\/\/www-test.absglobal.com\/br\/?post_type=abs_news_article&#038;p=5445"},"modified":"2021-11-11T09:19:50","modified_gmt":"2021-11-11T14:19:50","slug":"mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite","status":"publish","type":"abs_news_article","link":"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/","title":{"rendered":"Mais Produtividade: embri\u00f5es ABS levam melhoramento gen\u00e9tico para pequenos produtores de leite"},"content":{"rendered":"\n<p><em>O pecuarista Luiz Paulo Canzian comemora o progresso gen\u00e9tico acelerado do seu rebanho; iniciativa oferece gen\u00e9tica de qualidade superior por meio da transfer\u00eancia de embri\u00f5es (TE)<\/em><\/p>\n\n\n\n<p>O melhoramento gen\u00e9tico acelerado est\u00e1 promovendo excelentes resultados para pequenos produtores de leite, por meio do Mais Produtividade \u2013 produto da ABS destinado \u00e0 oferta de embri\u00f5es para pecuaristas associados a latic\u00ednios e cooperativas.<\/p>\n\n\n\n<p>No Esp\u00edrito Santo, o produtor Luiz Paulo Canzian, associado \u00e0 Cooperativa de Latic\u00ednios Selita, comanda um dos rebanhos que recebeu os embri\u00f5es ABS na sua propriedade, a Fazenda Cupido, em Muqui (ES). Por meio da parceria entre a ABS e o Sebrae, a empresa disponibiliza embri\u00f5es Mais Produtividade para potencializar o progresso gen\u00e9tico dos rebanhos, multiplicando a produ\u00e7\u00e3o de leite.<\/p>\n\n\n\n<p>&#8220;O Mais Produtividade veio para antecipar 20 anos de melhoramento gen\u00e9tico, aqui no Esp\u00edrito Santo. Antigamente, quando se falava de transfer\u00eancia de embri\u00f5es, era s\u00f3 para grandes produtores. Hoje, gra\u00e7as \u00e0 ABS, Sebrae e Cooperativa Selita, eu tenho acesso a um progresso gen\u00e9tico que n\u00e3o conseguiria de outra forma&#8221;, comemora Luiz Paulo.<\/p>\n\n\n\n<p>Hoje, as novilhas de dois anos de idade do produtor produzem em torno de 30 kg de leite por dia \u2013 um resultado sem precedentes para a propriedade, que abriga um rebanho Girolando meio-sangue.<\/p>\n\n\n\n<p>&#8220;Eu fico muito satisfeito, n\u00e3o s\u00f3 pela minha fazenda, mas por toda a regi\u00e3o, todos os pequenos produtores que est\u00e3o sendo valorizados por esta iniciativa. S\u00f3 tenho a agradecer a todos os envolvidos&#8221;, ressalta Luiz Paulo.<\/p>\n\n\n\n<p>O gerente de Neg\u00f3cios Embri\u00f5es da ABS, Pedro Ivo, explica que o Mais Produtividade \u00e9 desenvolvido com as necessidades reais de cada produtor em mente.<\/p>\n\n\n\n<p>&#8220;Com a tecnologia de TE, temos a possibilidade de entregar ao produtor uma gen\u00e9tica pronta, desenvolvida para aprimorar o padr\u00e3o racial e aumentar a quantidade de animais produtivos do rebanho, estabelecendo o grau de sangue mais adequado para cada fazenda. Dessa forma, o produtor passa a produzir mais leite com menos animais&#8221;, comenta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O pecuarista Luiz Paulo Canzian comemora o progresso gen\u00e9tico acelerado do seu rebanho; iniciativa oferece gen\u00e9tica de qualidade superior por meio da transfer\u00eancia de embri\u00f5es (TE) O melhoramento gen\u00e9tico acelerado est\u00e1 promovendo excelentes resultados para pequenos produtores de leite, por meio do Mais Produtividade \u2013 produto da ABS destinado \u00e0 oferta de embri\u00f5es para pecuaristas [&hellip;]<\/p>\n","protected":false},"author":342,"featured_media":5446,"template":"","abs_news_category":[73],"abs_news_tag":[76],"class_list":["post-5445","abs_news_article","type-abs_news_article","status-publish","has-post-thumbnail","hentry","abs_news_category-noticias","abs_news_tag-leite","ep_custom_result-leite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mais Produtividade: embri\u00f5es ABS levam melhoramento gen\u00e9tico para pequenos produtores de leite - ABS Global Brasil<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mais Produtividade: embri\u00f5es ABS levam melhoramento gen\u00e9tico para pequenos produtores de leite\" \/>\n<meta property=\"og:description\" content=\"O pecuarista Luiz Paulo Canzian comemora o progresso gen\u00e9tico acelerado do seu rebanho; iniciativa oferece gen\u00e9tica de qualidade superior por meio da transfer\u00eancia de embri\u00f5es (TE) O melhoramento gen\u00e9tico acelerado est\u00e1 promovendo excelentes resultados para pequenos produtores de leite, por meio do Mais Produtividade \u2013 produto da ABS destinado \u00e0 oferta de embri\u00f5es para pecuaristas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-11T14:19:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/11\/WhatsApp-Image-2021-10-26-at-10.27.37.jpeg?fit=1600%2C1200\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/\",\"name\":\"Mais Produtividade: embri\u00f5es ABS levam melhoramento gen\u00e9tico para pequenos produtores de leite - ABS Global Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/11\/WhatsApp-Image-2021-10-26-at-10.27.37.jpeg\",\"datePublished\":\"2021-11-11T14:19:49+00:00\",\"dateModified\":\"2021-11-11T14:19:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/#primaryimage\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/11\/WhatsApp-Image-2021-10-26-at-10.27.37.jpeg\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/11\/WhatsApp-Image-2021-10-26-at-10.27.37.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mais Produtividade: embri\u00f5es ABS levam melhoramento gen\u00e9tico para pequenos produtores de leite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"name\":\"ABS Global Brasil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\",\"name\":\"ABS Global Brasil\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Brasil \"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mais Produtividade: embri\u00f5es ABS levam melhoramento gen\u00e9tico para pequenos produtores de leite - ABS Global Brasil","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Mais Produtividade: embri\u00f5es ABS levam melhoramento gen\u00e9tico para pequenos produtores de leite","og_description":"O pecuarista Luiz Paulo Canzian comemora o progresso gen\u00e9tico acelerado do seu rebanho; iniciativa oferece gen\u00e9tica de qualidade superior por meio da transfer\u00eancia de embri\u00f5es (TE) O melhoramento gen\u00e9tico acelerado est\u00e1 promovendo excelentes resultados para pequenos produtores de leite, por meio do Mais Produtividade \u2013 produto da ABS destinado \u00e0 oferta de embri\u00f5es para pecuaristas [&hellip;]","og_url":"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/","og_site_name":"ABS Global Brasil","article_modified_time":"2021-11-11T14:19:50+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/11\/WhatsApp-Image-2021-10-26-at-10.27.37.jpeg?fit=1600%2C1200","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/","url":"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/","name":"Mais Produtividade: embri\u00f5es ABS levam melhoramento gen\u00e9tico para pequenos produtores de leite - ABS Global Brasil","isPartOf":{"@id":"https:\/\/www-test.absglobal.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/#primaryimage"},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/#primaryimage"},"thumbnailUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/11\/WhatsApp-Image-2021-10-26-at-10.27.37.jpeg","datePublished":"2021-11-11T14:19:49+00:00","dateModified":"2021-11-11T14:19:50+00:00","breadcrumb":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/#primaryimage","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/11\/WhatsApp-Image-2021-10-26-at-10.27.37.jpeg","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/11\/WhatsApp-Image-2021-10-26-at-10.27.37.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/mais-produtividade-embrioes-abs-levam-melhoramento-genetico-para-pequenos-produtores-de-leite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-test.absglobal.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www-test.absglobal.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Mais Produtividade: embri\u00f5es ABS levam melhoramento gen\u00e9tico para pequenos produtores de leite"}]},{"@type":"WebSite","@id":"https:\/\/www-test.absglobal.com\/br\/#website","url":"https:\/\/www-test.absglobal.com\/br\/","name":"ABS Global Brasil","description":"","publisher":{"@id":"https:\/\/www-test.absglobal.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www-test.absglobal.com\/br\/#organization","name":"ABS Global Brasil","url":"https:\/\/www-test.absglobal.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Brasil "},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article\/5445"}],"collection":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/users\/342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media\/5446"}],"wp:attachment":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media?parent=5445"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_category?post=5445"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_tag?post=5445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}