{"id":5216,"date":"2021-08-10T09:54:40","date_gmt":"2021-08-10T14:54:40","guid":{"rendered":"https:\/\/www-test.absglobal.com\/br\/?post_type=abs_news_article&#038;p=5216"},"modified":"2021-08-10T21:15:28","modified_gmt":"2021-08-11T02:15:28","slug":"maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica","status":"publish","type":"abs_news_article","link":"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/","title":{"rendered":"Maratona Gen\u00e9tica Corte ABS movimenta mercado durante a ExpoGen\u00e9tica"},"content":{"rendered":"\n<p><em>Ofertas especiais incluem s\u00eamen convencional, gen\u00e9tica sexada e embri\u00f5es; vendas ser\u00e3o feitas de forma 100% digital<\/em><\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/08\/Feed-2-e1628647783663.jpg\" alt=\"\" data-id=\"5222\" data-full-url=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/08\/Feed-2-e1628647783663.jpg\" data-link=\"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/feed-2\/\" class=\"wp-image-5222\" srcset=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/08\/Feed-2-e1628647783663.jpg 1000w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/08\/Feed-2-e1628647783663.jpg?resize=150,150 150w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/08\/Feed-2-e1628647783663.jpg?resize=300,300 300w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/08\/Feed-2-e1628647783663.jpg?resize=768,768 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>A 14\u00aa ExpoGen\u00e9tica j\u00e1 come\u00e7a com boas novidades para o produtor! De 14 a 16 de agosto, ofertas especiais de gen\u00e9tica bovina ser\u00e3o disponibilizadas durante a Maratona Gen\u00e9tica Corte ABS, levando o melhor das baterias Corte Zebu e Corte Europeu da empresa para o produtor com vendas 100% on-line.<\/p>\n\n\n\n<p>O coordenador de Produto e Atendimento ao Cliente Corte da ABS, Arthur Vieira, ressalta que ser\u00e3o feitas ofertas especiais de s\u00eamen convencional, gen\u00e9tica sexada Sexcel e embri\u00f5es.<\/p>\n\n\n\n<p>&#8220;Com a esta\u00e7\u00e3o de monta se aproximando, a Maratona Gen\u00e9tica Corte ABS \u00e9 uma oportunidade \u00fanica para o pecuarista adquirir o que h\u00e1 de melhor na gen\u00e9tica zebu\u00edna e taurina de corte. Selecionamos excelentes op\u00e7\u00f5es em touros melhoradores para que o produtor maximize a rentabilidade e a produtividade do rebanho de corte&#8221;, comenta Arthur.<\/p>\n\n\n\n<p>Durante a Maratona Gen\u00e9tica Corte, as vendas ser\u00e3o realizadas de forma 100% digital, permitindo que todos possam participar, independentemente do local. Para acessar as ofertas do evento, basta acessar o link: <a href=\"https:\/\/abs.link\/maratona\/corte\/\">https:\/\/abs.link\/maratona\/corte\/<\/a>.<\/p>\n\n\n\n<p><strong>ExpoGen\u00e9tica<\/strong>. A Maratona Gen\u00e9tica Corte ABS \u00e9 parte da programa\u00e7\u00e3o da empresa para a 14\u00aa ExpoGen\u00e9tica. Al\u00e9m da a\u00e7\u00e3o com ofertas especiais de gen\u00e9tica, a ABS tamb\u00e9m realizar\u00e1 a segunda edi\u00e7\u00e3o do RoadShow ABS, bem como o tradicional Desfile de Touros e o retorno das visitas presenciais \u00e0 Central ABS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ofertas especiais incluem s\u00eamen convencional, gen\u00e9tica sexada e embri\u00f5es; vendas ser\u00e3o feitas de forma 100% digital A 14\u00aa ExpoGen\u00e9tica j\u00e1 come\u00e7a com boas novidades para o produtor! De 14 a 16 de agosto, ofertas especiais de gen\u00e9tica bovina ser\u00e3o disponibilizadas durante a Maratona Gen\u00e9tica Corte ABS, levando o melhor das baterias Corte Zebu e Corte [&hellip;]<\/p>\n","protected":false},"author":342,"featured_media":0,"template":"","abs_news_category":[73],"abs_news_tag":[77],"class_list":["post-5216","abs_news_article","type-abs_news_article","status-publish","hentry","abs_news_category-noticias","abs_news_tag-corte","ep_custom_result-corte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Maratona Gen\u00e9tica Corte ABS movimenta mercado durante a ExpoGen\u00e9tica - ABS Global Brasil<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maratona Gen\u00e9tica Corte ABS movimenta mercado durante a ExpoGen\u00e9tica\" \/>\n<meta property=\"og:description\" content=\"Ofertas especiais incluem s\u00eamen convencional, gen\u00e9tica sexada e embri\u00f5es; vendas ser\u00e3o feitas de forma 100% digital A 14\u00aa ExpoGen\u00e9tica j\u00e1 come\u00e7a com boas novidades para o produtor! De 14 a 16 de agosto, ofertas especiais de gen\u00e9tica bovina ser\u00e3o disponibilizadas durante a Maratona Gen\u00e9tica Corte ABS, levando o melhor das baterias Corte Zebu e Corte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-11T02:15:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/08\/Feed-2-e1628647783663.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/\",\"name\":\"Maratona Gen\u00e9tica Corte ABS movimenta mercado durante a ExpoGen\u00e9tica - ABS Global Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/08\/Feed-2-e1628647783663.jpg\",\"datePublished\":\"2021-08-10T14:54:40+00:00\",\"dateModified\":\"2021-08-11T02:15:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/#primaryimage\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/08\/Feed-2-e1628647783663.jpg\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/08\/Feed-2-e1628647783663.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maratona Gen\u00e9tica Corte ABS movimenta mercado durante a ExpoGen\u00e9tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"name\":\"ABS Global Brasil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\",\"name\":\"ABS Global Brasil\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Brasil \"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Maratona Gen\u00e9tica Corte ABS movimenta mercado durante a ExpoGen\u00e9tica - ABS Global Brasil","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Maratona Gen\u00e9tica Corte ABS movimenta mercado durante a ExpoGen\u00e9tica","og_description":"Ofertas especiais incluem s\u00eamen convencional, gen\u00e9tica sexada e embri\u00f5es; vendas ser\u00e3o feitas de forma 100% digital A 14\u00aa ExpoGen\u00e9tica j\u00e1 come\u00e7a com boas novidades para o produtor! De 14 a 16 de agosto, ofertas especiais de gen\u00e9tica bovina ser\u00e3o disponibilizadas durante a Maratona Gen\u00e9tica Corte ABS, levando o melhor das baterias Corte Zebu e Corte [&hellip;]","og_url":"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/","og_site_name":"ABS Global Brasil","article_modified_time":"2021-08-11T02:15:28+00:00","og_image":[{"url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/08\/Feed-2-e1628647783663.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/","url":"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/","name":"Maratona Gen\u00e9tica Corte ABS movimenta mercado durante a ExpoGen\u00e9tica - ABS Global Brasil","isPartOf":{"@id":"https:\/\/www-test.absglobal.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/#primaryimage"},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/#primaryimage"},"thumbnailUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/08\/Feed-2-e1628647783663.jpg","datePublished":"2021-08-10T14:54:40+00:00","dateModified":"2021-08-11T02:15:28+00:00","breadcrumb":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/#primaryimage","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/08\/Feed-2-e1628647783663.jpg","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/08\/Feed-2-e1628647783663.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/maratona-genetica-corte-abs-movimenta-mercado-durante-a-expogenetica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-test.absglobal.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www-test.absglobal.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Maratona Gen\u00e9tica Corte ABS movimenta mercado durante a ExpoGen\u00e9tica"}]},{"@type":"WebSite","@id":"https:\/\/www-test.absglobal.com\/br\/#website","url":"https:\/\/www-test.absglobal.com\/br\/","name":"ABS Global Brasil","description":"","publisher":{"@id":"https:\/\/www-test.absglobal.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www-test.absglobal.com\/br\/#organization","name":"ABS Global Brasil","url":"https:\/\/www-test.absglobal.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Brasil "},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article\/5216"}],"collection":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/users\/342"}],"wp:attachment":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media?parent=5216"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_category?post=5216"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_tag?post=5216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}