{"id":5084,"date":"2021-07-06T14:09:23","date_gmt":"2021-07-06T19:09:23","guid":{"rendered":"https:\/\/www-test.absglobal.com\/br\/?post_type=abs_news_article&#038;p=5084"},"modified":"2021-07-08T07:54:26","modified_gmt":"2021-07-08T12:54:26","slug":"sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas","status":"publish","type":"abs_news_article","link":"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/","title":{"rendered":"Sum\u00e1rio Top100 Clarifide: ABS lidera 8 das 13 categorias avaliadas"},"content":{"rendered":"\n<p><em>Empresa de biotecnologia \u00e9 destaque absoluto nas avalia\u00e7\u00f5es, com 43% de todas as f\u00eameas contempladas<\/em><\/p>\n\n\n\n<p>O sum\u00e1rio Top100 Clarifide de 2021, lan\u00e7ado pela Zoetis na \u00faltima quinta-feira (1 de julho), revela, mais uma vez, a qualidade da gen\u00e9tica ABS. Na avalia\u00e7\u00e3o, que apresenta as 100 melhores f\u00eameas do Brasil (avaliadas pelo Clarifide) para 13 categorias, a empresa ocupa a lideran\u00e7a em oito quesitos, al\u00e9m de apresentar excelentes resultados nas provas gen\u00e9ticas de abril deste ano.<\/p>\n\n\n\n<p>Entre as categorias avaliadas, a gen\u00e9tica ABS domina nos \u00edndices (NM$, TPI, FM$ e DWP$), na produ\u00e7\u00e3o (leite, gordura e prote\u00edna) e, ainda, na sa\u00fade (vida produtiva), segundo explica o gerente T\u00e9cnico e Ferramentas Gen\u00e9ticas Leite da ABS, Diego Almeida.<\/p>\n\n\n\n<p>\u201cComo nas edi\u00e7\u00f5es anteriores, a ABS \u00e9 a empresa de biotecnologia que mais se destaca no sum\u00e1rio. \u00c9 motivo de grande orgulho para a equipe, pois comprova o resultado que o nosso melhoramento gen\u00e9tico \u00e9 capaz de oferecer\u201d, comenta.<\/p>\n\n\n\n<p>O gerente acrescenta: \u201cAs filhas de touros ABS dominam nos principais \u00edndices. Para M\u00e9rito L\u00edquido, 83% das f\u00eameas s\u00e3o prog\u00eanies de touros da nossa bateria, assim como 77% para TPI, 74% para M\u00e9rito Flu\u00eddo e 72% para DWP$. Nas caracter\u00edsticas de produ\u00e7\u00e3o, a ABS responde por 35% das f\u00eameas avaliadas para Leite; 73%, para Gordura e 50%, para Prote\u00edna. Na categoria Vida Produtiva, 37% das f\u00eameas t\u00eam gen\u00e9tica ABS\u201d, explica.<\/p>\n\n\n\n<p>No quadro geral, a predomin\u00e2ncia da ABS fica ainda mais clara: das 1300 f\u00eameas avaliadas, 538 s\u00e3o prog\u00eanies de touros ABS \u2013&nbsp;representando 43% de todos os animais. \u201cEntre os 5 touros que tiveram mais filhas no sum\u00e1rio, 4 s\u00e3o ABS: o ABS Crimson-ET lidera com 131 filhas, seguido pelo Pine-Tree Acura-ET, com 69 e, finalmente, ABS Achiever-ET e Denovo 7545 Diversity-ET, ambos com 32 prog\u00eanies\u201d, comenta Diego.<\/p>\n\n\n\n<p>A n\u00edvel individual, uma das bezerras mais bem avaliadas do sum\u00e1rio foi a 7203, filha do Pine-Tree Heroic-ET, que foi eleita a n\u00famero 1 para 5 categorias \u2013&nbsp;TPI, NM$, FM$, DWP$ e Gordura. A bezerra foi criada pelo produtor Marcos Epp, da Agropecu\u00e1ria Regia, em Palmeira (PR).<\/p>\n\n\n\n<p><strong>N\u00facleo NEO.<\/strong> Merece destaque, tamb\u00e9m, o desempenho das doadoras do N\u00facleo NEO da ABS, composto por f\u00eameas de valor gen\u00e9tico superior, comprovado por meio de avalia\u00e7\u00f5es gen\u00f4micas. As doadoras do N\u00facleo NEO formam a base da linha exclusiva de embri\u00f5es da empresa \u2013&nbsp;o ABS NEO e o ABS NEO Premium, com linhas de embri\u00f5es de alto padr\u00e3o.<\/p>\n\n\n\n<p>Na categoria NM$, a ABS soma 17 doadoras avaliadas, incluindo 4 entre as 10 primeiras do ranking. Para TPI, s\u00e3o 13 doadoras \u2013 contando com 2 no Top 10. Na categoria FM$, s\u00e3o mais 17 doadoras, com 3 entre as 10 melhores colocadas. Para DWP$, 12 doadoras do N\u00facleo se destacam, incluindo 2 no Top 10. Para Gordura e Prote\u00edna, a ABS conta 8 e 9 doadoras, respectivamente. Em ambas as categorias, a ABS tem uma doadora colocada entre as 10 melhores. Por fim, para Vida Produtiva, s\u00e3o 6 doadoras do N\u00facleo NEO, com uma em destaque no Top 10.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empresa de biotecnologia \u00e9 destaque absoluto nas avalia\u00e7\u00f5es, com 43% de todas as f\u00eameas contempladas O sum\u00e1rio Top100 Clarifide de 2021, lan\u00e7ado pela Zoetis na \u00faltima quinta-feira (1 de julho), revela, mais uma vez, a qualidade da gen\u00e9tica ABS. Na avalia\u00e7\u00e3o, que apresenta as 100 melhores f\u00eameas do Brasil (avaliadas pelo Clarifide) para 13 categorias, [&hellip;]<\/p>\n","protected":false},"author":342,"featured_media":5085,"template":"","abs_news_category":[73],"abs_news_tag":[76],"class_list":["post-5084","abs_news_article","type-abs_news_article","status-publish","has-post-thumbnail","hentry","abs_news_category-noticias","abs_news_tag-leite","ep_custom_result-leite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sum\u00e1rio Top100 Clarifide: ABS lidera 8 das 13 categorias avaliadas - ABS Global Brasil<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sum\u00e1rio Top100 Clarifide: ABS lidera 8 das 13 categorias avaliadas\" \/>\n<meta property=\"og:description\" content=\"Empresa de biotecnologia \u00e9 destaque absoluto nas avalia\u00e7\u00f5es, com 43% de todas as f\u00eameas contempladas O sum\u00e1rio Top100 Clarifide de 2021, lan\u00e7ado pela Zoetis na \u00faltima quinta-feira (1 de julho), revela, mais uma vez, a qualidade da gen\u00e9tica ABS. Na avalia\u00e7\u00e3o, que apresenta as 100 melhores f\u00eameas do Brasil (avaliadas pelo Clarifide) para 13 categorias, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-08T12:54:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/07\/WhatsApp-Image-2021-07-02-at-16.32.47.jpeg?fit=1024%2C766\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"766\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/\",\"name\":\"Sum\u00e1rio Top100 Clarifide: ABS lidera 8 das 13 categorias avaliadas - ABS Global Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/07\/WhatsApp-Image-2021-07-02-at-16.32.47.jpeg\",\"datePublished\":\"2021-07-06T19:09:23+00:00\",\"dateModified\":\"2021-07-08T12:54:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/#primaryimage\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/07\/WhatsApp-Image-2021-07-02-at-16.32.47.jpeg\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/07\/WhatsApp-Image-2021-07-02-at-16.32.47.jpeg\",\"width\":1024,\"height\":766},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sum\u00e1rio Top100 Clarifide: ABS lidera 8 das 13 categorias avaliadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"name\":\"ABS Global Brasil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\",\"name\":\"ABS Global Brasil\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Brasil \"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sum\u00e1rio Top100 Clarifide: ABS lidera 8 das 13 categorias avaliadas - ABS Global Brasil","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Sum\u00e1rio Top100 Clarifide: ABS lidera 8 das 13 categorias avaliadas","og_description":"Empresa de biotecnologia \u00e9 destaque absoluto nas avalia\u00e7\u00f5es, com 43% de todas as f\u00eameas contempladas O sum\u00e1rio Top100 Clarifide de 2021, lan\u00e7ado pela Zoetis na \u00faltima quinta-feira (1 de julho), revela, mais uma vez, a qualidade da gen\u00e9tica ABS. Na avalia\u00e7\u00e3o, que apresenta as 100 melhores f\u00eameas do Brasil (avaliadas pelo Clarifide) para 13 categorias, [&hellip;]","og_url":"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/","og_site_name":"ABS Global Brasil","article_modified_time":"2021-07-08T12:54:26+00:00","og_image":[{"width":1024,"height":766,"url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/07\/WhatsApp-Image-2021-07-02-at-16.32.47.jpeg?fit=1024%2C766","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/","url":"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/","name":"Sum\u00e1rio Top100 Clarifide: ABS lidera 8 das 13 categorias avaliadas - ABS Global Brasil","isPartOf":{"@id":"https:\/\/www-test.absglobal.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/#primaryimage"},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/#primaryimage"},"thumbnailUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/07\/WhatsApp-Image-2021-07-02-at-16.32.47.jpeg","datePublished":"2021-07-06T19:09:23+00:00","dateModified":"2021-07-08T12:54:26+00:00","breadcrumb":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/#primaryimage","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/07\/WhatsApp-Image-2021-07-02-at-16.32.47.jpeg","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/07\/WhatsApp-Image-2021-07-02-at-16.32.47.jpeg","width":1024,"height":766},{"@type":"BreadcrumbList","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/sumario-top100-clarifide-abs-lidera-8-das-13-categorias-avaliadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-test.absglobal.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www-test.absglobal.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"Sum\u00e1rio Top100 Clarifide: ABS lidera 8 das 13 categorias avaliadas"}]},{"@type":"WebSite","@id":"https:\/\/www-test.absglobal.com\/br\/#website","url":"https:\/\/www-test.absglobal.com\/br\/","name":"ABS Global Brasil","description":"","publisher":{"@id":"https:\/\/www-test.absglobal.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www-test.absglobal.com\/br\/#organization","name":"ABS Global Brasil","url":"https:\/\/www-test.absglobal.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Brasil "},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article\/5084"}],"collection":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/users\/342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media\/5085"}],"wp:attachment":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media?parent=5084"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_category?post=5084"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_tag?post=5084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}