{"id":4692,"date":"2021-01-26T12:06:19","date_gmt":"2021-01-26T17:06:19","guid":{"rendered":"http:\/\/www-test.absglobal.com\/br\/?post_type=abs_news_article&#038;p=4692"},"modified":"2021-01-26T12:06:20","modified_gmt":"2021-01-26T17:06:20","slug":"abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento","status":"publish","type":"abs_news_article","link":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/","title":{"rendered":"ABS XBlack: base de dados do \u00edndice exclusivo da ABS est\u00e1 em crescimento"},"content":{"rendered":"\n<p><em>Com mais uma propriedade colaborando para o desenvolvimento do \u00edndice econ\u00f4mico, ABS XBlack est\u00e1 mais completo que nunca<\/em><\/p>\n\n\n\n<p>O ABS XBlack, \u00edndice econ\u00f4mico desenvolvido pela ABS com exclusividade para apontar os touros de melhor desempenho para sistemas de cruzamento industrial, conta com uma base de dados cada vez maior e mais consistente, para oferecer ao cliente informa\u00e7\u00f5es precisas e completas.<\/p>\n\n\n\n<p>A Fazenda Seriema, localizada em Miranda (MS), \u00e9 a mais recente colaboradora do \u00edndice, juntando-se a propriedades de seis Estados brasileiros (Mato Grosso, Mato Grosso do Sul, S\u00e3o Paulo, Par\u00e1, Tocantins e Rond\u00f4nia) cujos rebanhos contribuem para o desenvolvimento do ABS XBlack.<\/p>\n\n\n\n<p>&#8220;O \u00edndice \u00e9 gerado a partir de dados do mundo real, coletados em fazendas nacionais, com rebanhos avaliados geneticamente e controlados, com o objetivo de conferir mais seguran\u00e7a \u00e0s informa\u00e7\u00f5es disponibilizadas ao produtor. O ABS XBlack analisa as DEPs e fatores de maior impacto para a rentabilidade do pecuarista: ganho de peso, efici\u00eancia alimentar e carca\u00e7a de alta qualidade&#8221;, explica o gerente de Produto e Projetos Corte Europeu, Marcelo Selistre.<\/p>\n\n\n\n<p>O papel das fazendas parceiras do projeto \u00e9 fundamental, j\u00e1 que s\u00e3o os dados coletados a campo que fundamentam a avalia\u00e7\u00e3o dos touros ranqueados pelo \u00edndice, facilitando a escolha do melhor animal para aumentar os ganhos econ\u00f4micos em sistemas de cruzamento industrial.<\/p>\n\n\n\n<p>Com mais de 80 mil dados de prog\u00eanies F1 avaliados, o ABS XBlack \u00e9 a melhor solu\u00e7\u00e3o para o produtor de carne que procura os melhores touros para ganho gen\u00e9tico no cruzamento industrial. Tudo isso, levando em considera\u00e7\u00e3o os pre\u00e7os e valores praticados no mercado brasileiro, oferecendo informa\u00e7\u00f5es fi\u00e9is \u00e0 realidade para clientes nacionais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com mais uma propriedade colaborando para o desenvolvimento do \u00edndice econ\u00f4mico, ABS XBlack est\u00e1 mais completo que nunca O ABS XBlack, \u00edndice econ\u00f4mico desenvolvido pela ABS com exclusividade para apontar os touros de melhor desempenho para sistemas de cruzamento industrial, conta com uma base de dados cada vez maior e mais consistente, para oferecer ao [&hellip;]<\/p>\n","protected":false},"author":342,"featured_media":4693,"template":"","abs_news_category":[73],"abs_news_tag":[81],"class_list":["post-4692","abs_news_article","type-abs_news_article","status-publish","has-post-thumbnail","hentry","abs_news_category-noticias","abs_news_tag-carne","ep_custom_result-carne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ABS XBlack: base de dados do \u00edndice exclusivo da ABS est\u00e1 em crescimento - ABS Global Brasil<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABS XBlack: base de dados do \u00edndice exclusivo da ABS est\u00e1 em crescimento\" \/>\n<meta property=\"og:description\" content=\"Com mais uma propriedade colaborando para o desenvolvimento do \u00edndice econ\u00f4mico, ABS XBlack est\u00e1 mais completo que nunca O ABS XBlack, \u00edndice econ\u00f4mico desenvolvido pela ABS com exclusividade para apontar os touros de melhor desempenho para sistemas de cruzamento industrial, conta com uma base de dados cada vez maior e mais consistente, para oferecer ao [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-26T17:06:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/01\/a.jpg?fit=640%2C480\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/\",\"name\":\"ABS XBlack: base de dados do \u00edndice exclusivo da ABS est\u00e1 em crescimento - ABS Global Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/01\/a.jpg\",\"datePublished\":\"2021-01-26T17:06:19+00:00\",\"dateModified\":\"2021-01-26T17:06:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/#primaryimage\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/01\/a.jpg\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/01\/a.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ABS XBlack: base de dados do \u00edndice exclusivo da ABS est\u00e1 em crescimento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"name\":\"ABS Global Brasil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\",\"name\":\"ABS Global Brasil\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Brasil \"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ABS XBlack: base de dados do \u00edndice exclusivo da ABS est\u00e1 em crescimento - ABS Global Brasil","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"ABS XBlack: base de dados do \u00edndice exclusivo da ABS est\u00e1 em crescimento","og_description":"Com mais uma propriedade colaborando para o desenvolvimento do \u00edndice econ\u00f4mico, ABS XBlack est\u00e1 mais completo que nunca O ABS XBlack, \u00edndice econ\u00f4mico desenvolvido pela ABS com exclusividade para apontar os touros de melhor desempenho para sistemas de cruzamento industrial, conta com uma base de dados cada vez maior e mais consistente, para oferecer ao [&hellip;]","og_url":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/","og_site_name":"ABS Global Brasil","article_modified_time":"2021-01-26T17:06:20+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/01\/a.jpg?fit=640%2C480","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/","url":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/","name":"ABS XBlack: base de dados do \u00edndice exclusivo da ABS est\u00e1 em crescimento - ABS Global Brasil","isPartOf":{"@id":"https:\/\/www-test.absglobal.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/#primaryimage"},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/#primaryimage"},"thumbnailUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/01\/a.jpg","datePublished":"2021-01-26T17:06:19+00:00","dateModified":"2021-01-26T17:06:20+00:00","breadcrumb":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/#primaryimage","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/01\/a.jpg","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2021\/01\/a.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-xblack-base-de-dados-do-indice-exclusivo-da-abs-esta-em-crescimento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-test.absglobal.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www-test.absglobal.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"ABS XBlack: base de dados do \u00edndice exclusivo da ABS est\u00e1 em crescimento"}]},{"@type":"WebSite","@id":"https:\/\/www-test.absglobal.com\/br\/#website","url":"https:\/\/www-test.absglobal.com\/br\/","name":"ABS Global Brasil","description":"","publisher":{"@id":"https:\/\/www-test.absglobal.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www-test.absglobal.com\/br\/#organization","name":"ABS Global Brasil","url":"https:\/\/www-test.absglobal.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Brasil "},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article\/4692"}],"collection":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/users\/342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media\/4693"}],"wp:attachment":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media?parent=4692"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_category?post=4692"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_tag?post=4692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}