{"id":10330,"date":"2024-09-02T13:34:04","date_gmt":"2024-09-02T18:34:04","guid":{"rendered":"https:\/\/www-test.absglobal.com\/br\/?post_type=abs_news_article&#038;p=10330"},"modified":"2024-09-02T13:34:08","modified_gmt":"2024-09-02T18:34:08","slug":"abs-anuncia-novo-comando-para-america-latina","status":"publish","type":"abs_news_article","link":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/","title":{"rendered":"ABS anuncia novo comando para Am\u00e9rica Latina"},"content":{"rendered":"\n<p><em>O veterin\u00e1rio Luis Adriano Teixeira assume a diretoria regional a partir do m\u00eas de setembro<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" height=\"1024\" width=\"834\" src=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/09\/Luis-Adriano-Teixeira-novo-Diretor-Comercial-da-ABS-na-America-Latina.jpg?w=834\" alt=\"\" class=\"wp-image-10331\" srcset=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/09\/Luis-Adriano-Teixeira-novo-Diretor-Comercial-da-ABS-na-America-Latina.jpg 3024w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/09\/Luis-Adriano-Teixeira-novo-Diretor-Comercial-da-ABS-na-America-Latina.jpg?resize=244,300 244w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/09\/Luis-Adriano-Teixeira-novo-Diretor-Comercial-da-ABS-na-America-Latina.jpg?resize=768,943 768w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/09\/Luis-Adriano-Teixeira-novo-Diretor-Comercial-da-ABS-na-America-Latina.jpg?resize=834,1024 834w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/09\/Luis-Adriano-Teixeira-novo-Diretor-Comercial-da-ABS-na-America-Latina.jpg?resize=1251,1536 1251w, https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/09\/Luis-Adriano-Teixeira-novo-Diretor-Comercial-da-ABS-na-America-Latina.jpg?resize=1668,2048 1668w\" sizes=\"(max-width: 834px) 100vw, 834px\" \/><\/figure>\n\n\n\n<p>A ABS divulgou esta semana mudan\u00e7a na gest\u00e3o da empresa. Ricardo Campos, atual Diretor para Am\u00e9rica Latina, assume novo cargo de Diretor Global da \u00e1rea Comercial e de \u00e1reas estrat\u00e9gicas de suporte.\u00a0 O seu sucessor ser\u00e1 o reconhecido e experiente especialista brasileiro Luis Adriano Teixeira.<\/p>\n\n\n\n<p>\u201cCom muita felicidade e entusiasmo, recebi a comunica\u00e7\u00e3o do meu novo desafio. Tenho confian\u00e7a de que seguiremos avan\u00e7ando com foco nos atuais e novos pilares estrat\u00e9gicos. Estou confiante, porque temos um excelente time de profissionais altamente qualificado e uma lideran\u00e7a clara de mercado, fruto da nossa tecnologia, esp\u00edrito inovador e entrega de estrat\u00e9gias disruptivas e eficientes&#8221;, comentou o novo Diretor Comercial da ABS na Am\u00e9rica Latina, deixando claro seu objetivo de focar na cria\u00e7\u00e3o de valor para os clientes ABS e diferencia\u00e7\u00e3o da empresa no mercado.<br><\/p>\n\n\n\n<p>Luis Adriano \u00e9 m\u00e9dico veterin\u00e1rio formado pela FMVZ-USP de S\u00e3o Paulo (SP), com MBA em Gest\u00e3o do Agroneg\u00f3cio pela FGV de Ribeir\u00e3o Preto (SP). Ele integra a equipe ABS h\u00e1 5 anos, per\u00edodo em que atuou como Gerente Contas Estrat\u00e9gicas Corte ABS para Am\u00e9rica Latina.<\/p>\n\n\n\n<p>Ricardo Campos, que entrega o comando da regi\u00e3o, comenta que Lu\u00eds Adriano carrega claramente a miss\u00e3o e os valores da empresa. &#8220;Com a certeza, sob sua lideran\u00e7a, a ABS na Am\u00e9rica Latina continuar\u00e1 se destacando e crescendo exponencialmente&#8221;, refor\u00e7ou o novo Diretor Comercial Global da ABS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O veterin\u00e1rio Luis Adriano Teixeira assume a diretoria regional a partir do m\u00eas de setembro A ABS divulgou esta semana mudan\u00e7a na gest\u00e3o da empresa. Ricardo Campos, atual Diretor para Am\u00e9rica Latina, assume novo cargo de Diretor Global da \u00e1rea Comercial e de \u00e1reas estrat\u00e9gicas de suporte.\u00a0 O seu sucessor ser\u00e1 o reconhecido e experiente [&hellip;]<\/p>\n","protected":false},"author":10336,"featured_media":0,"template":"","abs_news_category":[],"abs_news_tag":[],"class_list":["post-10330","abs_news_article","type-abs_news_article","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ABS anuncia novo comando para Am\u00e9rica Latina - ABS Global Brasil<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABS anuncia novo comando para Am\u00e9rica Latina\" \/>\n<meta property=\"og:description\" content=\"O veterin\u00e1rio Luis Adriano Teixeira assume a diretoria regional a partir do m\u00eas de setembro A ABS divulgou esta semana mudan\u00e7a na gest\u00e3o da empresa. Ricardo Campos, atual Diretor para Am\u00e9rica Latina, assume novo cargo de Diretor Global da \u00e1rea Comercial e de \u00e1reas estrat\u00e9gicas de suporte.\u00a0 O seu sucessor ser\u00e1 o reconhecido e experiente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/\" \/>\n<meta property=\"og:site_name\" content=\"ABS Global Brasil\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-02T18:34:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/09\/Luis-Adriano-Teixeira-novo-Diretor-Comercial-da-ABS-na-America-Latina.jpg?w=834\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/\",\"name\":\"ABS anuncia novo comando para Am\u00e9rica Latina - ABS Global Brasil\",\"isPartOf\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/09\/Luis-Adriano-Teixeira-novo-Diretor-Comercial-da-ABS-na-America-Latina.jpg?w=834\",\"datePublished\":\"2024-09-02T18:34:04+00:00\",\"dateModified\":\"2024-09-02T18:34:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/#primaryimage\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/09\/Luis-Adriano-Teixeira-novo-Diretor-Comercial-da-ABS-na-America-Latina.jpg\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/09\/Luis-Adriano-Teixeira-novo-Diretor-Comercial-da-ABS-na-America-Latina.jpg\",\"width\":3024,\"height\":3712},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www-test.absglobal.com\/br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ABS anuncia novo comando para Am\u00e9rica Latina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#website\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"name\":\"ABS Global Brasil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#organization\",\"name\":\"ABS Global Brasil\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"contentUrl\":\"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png\",\"width\":872,\"height\":1080,\"caption\":\"ABS Global Brasil \"},\"image\":{\"@id\":\"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ABS anuncia novo comando para Am\u00e9rica Latina - ABS Global Brasil","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"ABS anuncia novo comando para Am\u00e9rica Latina","og_description":"O veterin\u00e1rio Luis Adriano Teixeira assume a diretoria regional a partir do m\u00eas de setembro A ABS divulgou esta semana mudan\u00e7a na gest\u00e3o da empresa. Ricardo Campos, atual Diretor para Am\u00e9rica Latina, assume novo cargo de Diretor Global da \u00e1rea Comercial e de \u00e1reas estrat\u00e9gicas de suporte.\u00a0 O seu sucessor ser\u00e1 o reconhecido e experiente [&hellip;]","og_url":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/","og_site_name":"ABS Global Brasil","article_modified_time":"2024-09-02T18:34:08+00:00","og_image":[{"url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/09\/Luis-Adriano-Teixeira-novo-Diretor-Comercial-da-ABS-na-America-Latina.jpg?w=834","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/","url":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/","name":"ABS anuncia novo comando para Am\u00e9rica Latina - ABS Global Brasil","isPartOf":{"@id":"https:\/\/www-test.absglobal.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/#primaryimage"},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/#primaryimage"},"thumbnailUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/09\/Luis-Adriano-Teixeira-novo-Diretor-Comercial-da-ABS-na-America-Latina.jpg?w=834","datePublished":"2024-09-02T18:34:04+00:00","dateModified":"2024-09-02T18:34:08+00:00","breadcrumb":{"@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/#primaryimage","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/09\/Luis-Adriano-Teixeira-novo-Diretor-Comercial-da-ABS-na-America-Latina.jpg","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2024\/09\/Luis-Adriano-Teixeira-novo-Diretor-Comercial-da-ABS-na-America-Latina.jpg","width":3024,"height":3712},{"@type":"BreadcrumbList","@id":"https:\/\/www-test.absglobal.com\/br\/noticias\/abs-anuncia-novo-comando-para-america-latina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www-test.absglobal.com\/br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www-test.absglobal.com\/br\/noticias\/"},{"@type":"ListItem","position":3,"name":"ABS anuncia novo comando para Am\u00e9rica Latina"}]},{"@type":"WebSite","@id":"https:\/\/www-test.absglobal.com\/br\/#website","url":"https:\/\/www-test.absglobal.com\/br\/","name":"ABS Global Brasil","description":"","publisher":{"@id":"https:\/\/www-test.absglobal.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www-test.absglobal.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www-test.absglobal.com\/br\/#organization","name":"ABS Global Brasil","url":"https:\/\/www-test.absglobal.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","contentUrl":"https:\/\/www-test.absglobal.com\/br\/wp-content\/uploads\/sites\/16\/2020\/03\/LogoRGB.png","width":872,"height":1080,"caption":"ABS Global Brasil "},"image":{"@id":"https:\/\/www-test.absglobal.com\/br\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article\/10330"}],"collection":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_article"}],"about":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/types\/abs_news_article"}],"author":[{"embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/users\/10336"}],"wp:attachment":[{"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/media?parent=10330"}],"wp:term":[{"taxonomy":"abs_news_category","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_category?post=10330"},{"taxonomy":"abs_news_tag","embeddable":true,"href":"https:\/\/www-test.absglobal.com\/br\/wp-json\/wp\/v2\/abs_news_tag?post=10330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}